{"id":970,"date":"2025-05-24T22:50:36","date_gmt":"2025-05-24T22:50:36","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=970"},"modified":"2025-05-24T22:50:37","modified_gmt":"2025-05-24T22:50:37","slug":"riquelme-quiere-a-russo-en-boca-y-espera-un-traspie-de-san-lorenzo","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2025\/05\/24\/riquelme-quiere-a-russo-en-boca-y-espera-un-traspie-de-san-lorenzo\/","title":{"rendered":"RIQUELME QUIERE A RUSSO EN BOCA Y ESPERA UN TRASPI\u00c9 DE SAN LORENZO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fue el primer DT de su gesti\u00f3n y vuelve a la carga por \u00e9l con vistas al Mundial de Clubes.<a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.radiosudamericana.com%2Fnota%2Fdeportes%2F327234-Riquelme-quiere-a-Russo-en-Boca-y-espera-un-traspie-de-San-Lorenzo.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Boca ya eligi\u00f3 a su t\u00e9cnico&nbsp;y es un viejo conocido de la casa. Se trata de&nbsp;Miguel \u00c1ngel Russo, el actual entrenador de San Lorenzo&nbsp;que disputar\u00e1 este domingo las semifinales del torneo Apertura ante Platense y que tiene contrato con el Cicl\u00f3n hasta diciembre de 2025<\/strong>. Tras la negativa de Gabriel Milito, quien declin\u00f3 el llamado del Xeneize, Juan Rom\u00e1n Riquelme resolvi\u00f3 esperar a Russo hasta \u00faltimo momento y ofrecerle nuevamente el buzo a quien fue el primer DT de gesti\u00f3n, con el que obtuvo la Superliga 2019\/2020 y al que despidi\u00f3 en agosto de 2021 tras una seguidilla de malos resultados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El presidente termin\u00f3 de tomar la decisi\u00f3n este jueves por la noche, tras varias horas de charla con los miembros del Consejo de F\u00fatbol.<\/strong>&nbsp;Si bien todos los ca\u00f1ones apuntaban a Milito,&nbsp;Riquelme tuvo siempre a mano el nombre de Miguel Russo, con quien fue campe\u00f3n en Boca de la Copa Libertadores 2007 y con quien lo une una relaci\u00f3n de amistad. Boca ten\u00eda pensado avanzar por Russo desde el inicio de los playoffs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero San Lorenzo fue superando instancias (venci\u00f3 a Tigre en octavos y a Argentinos en cuartos de final) y la dirigencia se tom\u00f3 72 horas para definir los pasos a seguir. Sab\u00eda que&nbsp;Gustavo Quinteros estaba listo para asumir, pero Russo contaba con ventaja por ser un hombre de confianza de Riquelme, por conocer los pasillos del club y tambi\u00e9n a varios integrantes del plantel azul y oro (Javier Garc\u00eda, Marcos Rojo, Frank Fabra, Exequiel Zeballos, Esteban Rol\u00f3n).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El tema, ahora, son los plazos. Porque&nbsp;Russo dirigir\u00e1 este domingo ante Platense y si avanza a la final reci\u00e9n estar\u00eda en condiciones de asumir el lunes 2 de junio, siete d\u00edas antes del viaje al Mundial de Clubes.<\/strong>&nbsp;El plantel de Boca retomar\u00e1 al trabajo este martes y la idea es que Russo conduzca el entrenamiento en Ezeiza, aunque todo depender\u00e1 de lo que ocurra el fin de semana. Si Miguel no est\u00e1 disponible, quien estar\u00eda a cargo de los trabajos ser\u00eda Silvio Rudman, el DT de la Reserva, o Roberto Pompei, su ayudante.&nbsp;Mariano Herr\u00f3n, quien no logr\u00f3 un buen&nbsp;feeling&nbsp;con los jugadores, analiza dejar el club y buscar nuevos horizontes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que pareciera ser un hecho es que el t\u00e9cnico no seguir\u00e1 en el Cicl\u00f3n pese a tener contrato vigente hasta diciembre de 2025. Russo sac\u00f3 a flote al equipo de Boedo en medio del caos institucional que vive la instituci\u00f3n, con una importante deuda con el plantel y el cuerpo t\u00e9cnico (el jueves anterior, los futbolistas se negaron a entrenar) y con muy poco margen para competir en el mercado de pases. De hecho,&nbsp;en San Lorenzo ve\u00edan venir el portazo&nbsp;en caso de que el equipo cayera el lunes pasado en La Paternal, un par de horas antes de que Boca cayera con el Rojo. Del lado del entrenador niegan todo tipo de contacto con el Xeneize, mientras aseguran que&nbsp;\u201csolo falta la oficializaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace unos d\u00edas, Russo comparti\u00f3 una ronda de caf\u00e9 con periodistas de San Lorenzo y antes de sentarse a las mesa aclar\u00f3 que no har\u00eda menci\u00f3n al tema.&nbsp;\u201cNo me pregunten de Boca porque no voy a decir una palabra\u201d. No abri\u00f3 ni cerr\u00f3 la puerta, pero dej\u00f3 entrever que los contactos exist\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque la salida de Russo de Boca no fue del todo prolija (el t\u00e9cnico quer\u00eda seguir y fue echado dos semanas despu\u00e9s de eliminar a River en la Copa Argentina, sinti\u00e9ndose v\u00edctima de una operaci\u00f3n de desgaste para quitarlo del cargo), Miguel y Riquelme mantuvieron el v\u00ednculo intacto. \u201cSigo hablando y me manda mensajes.&nbsp;Yo lo considero un amigo. Me pone contento que sea presidente de Boca. Ojal\u00e1 todo lo que piensa y lo que desarrolla se haga realidad\u201d, cont\u00f3 Russo tras la victoria de Rom\u00e1n en las urnas, en diciembre de 2023. Una semana atr\u00e1s, Riquelme hab\u00eda llamado a Miguel para felicitarlo por el triunfo por penales sobre River, en semifinales de la Copa de la Liga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La idea de Riquelme es que Russo&nbsp;firme contrato con Boca por un a\u00f1o. En su anterior paso, el t\u00e9cnico tuvo como ayudantes a Leandro Somoza y Mariano Herr\u00f3n, quien se hab\u00eda sumado por recomendaci\u00f3n de la dirigencia. Esta vez, Miguel llegar\u00eda con&nbsp;Claudio \u00dabeda&nbsp;como asistente principal y el colombiano Juvenal Rodr\u00edguez como alterno, con Juan Carlos Docabo como preparador de los arqueros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 puede hacer caer la llegada de Russo a Boca?&nbsp;Que el t\u00e9cnico decida finalmente quedarse en el Cicl\u00f3n -cosa poco probable a esta altura- o que desde San Lorenzo busquen empiojar las negociaciones haciendo valer los seis meses que le quedan de contrato. De ser necesario, en Boca est\u00e1n dispuestos a desembolsar una suma de dinero para lograr destrabar la salida del DT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si todo marcha bien,&nbsp;Boca volver\u00e1 al Mundial de Clubes con el mismo entrenador con el que compiti\u00f3 por \u00faltima vez&nbsp;en el m\u00e1ximo certamen intercontinental. En 2007, el Xeneize venci\u00f3 1 a 0 al \u00c9toile Sportive de Turqu\u00eda y cay\u00f3 4 a 2 en la final ante el Milan, que se tom\u00f3 revancha de la derrota en 2023. De regreso a Buenos Aires, el t\u00e9cnico no acept\u00f3 las condiciones de Boca para renovar su v\u00ednculo y, tras seis meses sin dirigir, recal\u00f3 justamente en San Lorenzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, a punto de cumplir&nbsp;70 a\u00f1os, el DT est\u00e1 a un paso de asumir un nuevo reto. Incluso, hasta comenzaron a trascender los puestos que el t\u00e9cnico buscar\u00eda reforzar de cara al Mundial de Clubes. Este domingo, la mira estar\u00e1 puesta en el Gas\u00f3metro. Mientras Russo busque el boleto a la final, Riquelme har\u00e1 fuerza por Platense. El tiempo pondr\u00e1 las cosas en su lugar.&nbsp;Y el lugar de Russo estar\u00eda otra vez en Boca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue el primer DT de su gesti\u00f3n y vuelve a la carga por \u00e9l con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=970"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/970\/revisions"}],"predecessor-version":[{"id":972,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/970\/revisions\/972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/971"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}