{"id":964,"date":"2025-05-24T22:47:06","date_gmt":"2025-05-24T22:47:06","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=964"},"modified":"2025-05-24T22:47:06","modified_gmt":"2025-05-24T22:47:06","slug":"di-maria-confirmo-su-salida-del-benfica-fue-mi-ultimo-partido-con-esta-camiseta","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2025\/05\/24\/di-maria-confirmo-su-salida-del-benfica-fue-mi-ultimo-partido-con-esta-camiseta\/","title":{"rendered":"DI MAR\u00cdA CONFIRM\u00d3 SU SALIDA DEL BENFICA: &#8220;FUE MI \u00daLTIMO PARTIDO CON ESTA CAMISETA&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El futbolista argentino anunci\u00f3 que no renovar\u00e1 su contrato con el club portugu\u00e9s y se marchar\u00e1 como jugador libre. El domingo disputar\u00e1 la final de la Copa de Portugal ante Sporting, su \u00faltimo encuentro oficial con Las \u00c1guilas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.radiosudamericana.com%2Fnota%2Fdeportes%2F326918-Di-Maria-confirmo-su-salida-del-Benfica--Fue-mi-ultimo-partido-con-esta-camiseta.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c1ngel Di Mar\u00eda confirm\u00f3 este s\u00e1bado su salida del Benfica, club al que regres\u00f3 en 2023. Tras el empate 1 a 1 ante Braga, el atacante argentino revel\u00f3 que no continuar\u00e1 en el equipo portugu\u00e9s y que el partido disputado fue su \u00faltimo compromiso por liga con esa camiseta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u201cNo fue el resultado final que quer\u00edamos en el campeonato. Trabajamos mucho para poder lograr el objetivo. Duele mucho terminar de esta manera despu\u00e9s de un a\u00f1o tan largo. Fue mi \u00faltimo partido de campeonato con esta camiseta y estoy orgulloso de haber podido volver a vestirla\u201d<\/strong><\/em>, expres\u00f3 el rosarino en sus redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Benfica, que necesitaba ganar para seguir con chances, no pudo superar al Braga y termin\u00f3 cediendo la liga a su cl\u00e1sico rival. El Sporting de Lisboa se consagr\u00f3 campe\u00f3n del f\u00fatbol portugu\u00e9s tras vencer 2 a 0 al Vit\u00f3ria Guimar\u00e3es, logrando as\u00ed el 21\u00ba t\u00edtulo de su historia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Di Mar\u00eda, de 36 a\u00f1os, tendr\u00e1 a\u00fan un \u00faltimo partido oficial con Las \u00c1guilas: ser\u00e1 el pr\u00f3ximo domingo 25 de mayo, cuando el Benfica enfrente nuevamente al Sporting en la final de la Copa de Portugal.&nbsp;<em><strong>\u201cQueda una final el domingo y vamos a ir con toda la ganas y alegr\u00eda para conquistarla. Juntos como siempre. Gracias por el apoyo, benfiquistas\u201d<\/strong><\/em>, a\u00f1adi\u00f3 el campe\u00f3n del mundo en Qatar 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta decisi\u00f3n, Fideo no jugar\u00e1 el Mundial de Clubes 2025, donde Benfica participar\u00e1, ni se enfrentar\u00e1 a Boca Juniors, ya que su contrato finalizar\u00e1 antes del inicio del torneo en Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El futbolista argentino anunci\u00f3 que no renovar\u00e1 su contrato con el club portugu\u00e9s y se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":965,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=964"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/964\/revisions"}],"predecessor-version":[{"id":966,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/964\/revisions\/966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/965"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}