{"id":932,"date":"2025-03-24T22:07:11","date_gmt":"2025-03-24T22:07:11","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=932"},"modified":"2025-03-24T22:07:12","modified_gmt":"2025-03-24T22:07:12","slug":"una-joven-embarazada-fue-atacada-por-su-pitbull-esta-grave","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2025\/03\/24\/una-joven-embarazada-fue-atacada-por-su-pitbull-esta-grave\/","title":{"rendered":"UNA JOVEN EMBARAZADA FUE ATACADA POR SU PITBULL: EST\u00c1 GRAVE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La v\u00edctima, de 22 a\u00f1os, fue mordida en el brazo y en gran parte de la cara. Se trata del segundo incidente con un perro de esta raza en dos d\u00edas<a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.radiosudamericana.com%2Fnota%2Fpoliciales%2F324298-Una-joven-embarazada-fue-atacada-por-su-pitbull--esta-grave-.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una&nbsp;joven embarazada&nbsp;de cinco meses, vivi\u00f3 momentos de terror luego de ser&nbsp;mordida por su perro&nbsp;de raza&nbsp;pitbull&nbsp;en C\u00f3rdoba. El violento episodio ocurri\u00f3 este s\u00e1bado en una casa ubicada en la calle Escorial al 2400, en el barrio Maip\u00fa 1\u00b0 Secci\u00f3n de la capital cordobesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien se desconocen los detalles de c\u00f3mo se origino el ataque, medios locales confirmaron que el animal le dej\u00f3 una&nbsp;grave lesi\u00f3n en la cara y en el brazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante esa situaci\u00f3n,&nbsp;el servicio de emergencias actu\u00f3 r\u00e1pidamente para garantizar la estabilidad de la joven y su beb\u00e9. Inicialmente, la v\u00edctima fue trasladada al Hospital San Roque para recibir las primeras atenciones m\u00e9dicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a su estado de gestaci\u00f3n, fue derivada a la Nueva Maternidad Provincial para una evaluaci\u00f3n m\u00e1s espec\u00edfica, y luego, al Hospital C\u00f3rdoba, donde&nbsp;permanece bajo cuidado m\u00e9dico para controlar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto,&nbsp;la Polic\u00eda de C\u00f3rdoba inici\u00f3 una investigaci\u00f3n&nbsp;para determinar las circunstancias en las que se produjo el hecho, incluyendo el comportamiento del animal, las condiciones en las que se encontraba al momento del ataque y si estaba inscripto en el registro obligatorio. De todas formas, tras el incidente,&nbsp;el pitbull fue sacrificado&nbsp;mediante eutanasia por un m\u00e9dico veterinario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata del&nbsp;segundo incidente&nbsp;en los \u00faltimos d\u00edas que involucra a un perro de esta raza. El viernes, una mujer de 72 a\u00f1os fue atacada por un pitbull en barrio San Javier, de la ciudad de C\u00f3rdoba. La v\u00edctima cont\u00f3 que el animal de su vecina se escap\u00f3 de la casa del lado, a trav\u00e9s de un tejido met\u00e1lico, cuando ella paseaba a su propia mascota y fue directamente a atacarla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ataque le produjo cortes m\u00faltiples en la cara, el cuello y brazos por lo que tuvo que ser trasladada a la Cl\u00ednica Aconcagua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades recordaron la importancia de tomar precauciones al convivir con mascotas de este tipo de razas consideradas potencialmente peligrosas, y destacaron la necesidad de supervisi\u00f3n constante para evitar este tipo de situaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La v\u00edctima, de 22 a\u00f1os, fue mordida en el brazo y en gran parte de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=932"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/932\/revisions"}],"predecessor-version":[{"id":934,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/932\/revisions\/934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/933"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}