{"id":897,"date":"2025-01-14T11:45:55","date_gmt":"2025-01-14T11:45:55","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=897"},"modified":"2025-01-14T11:45:55","modified_gmt":"2025-01-14T11:45:55","slug":"asi-quedaron-los-precios-de-los-combustibles-en-corrientes","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2025\/01\/14\/asi-quedaron-los-precios-de-los-combustibles-en-corrientes\/","title":{"rendered":"AS\u00cd QUEDARON LOS PRECIOS DE LOS COMBUSTIBLES EN CORRIENTES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">los nuevos valores que aplic\u00f3 este viernes 3 de enero la petrolera YPF en la Capital correntina. La suba represent\u00f3 un 1,75% promedio en todo el pa\u00eds y se tratar\u00eda del menor porcentaje anunciado en comparaci\u00f3n al a\u00f1o pasado. \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan lo establecido en el Decreto 1134\/2024, publicado el pasado 30 de diciembre en el Bolet\u00edn Oficial, los nuevos precios ser\u00e1n v\u00e1lidos hasta el 31 de enero, debido a que se prev\u00e9 otro aumento para el 1\u00b0 de febrero. El mecanismo forma parte del proceso de sinceramiento de los precios propuesto por el Ministerio de Econom\u00eda, el cual toma como referencia las variaciones de la inflaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Es as\u00ed que, en Corrientes, el cronista de Sudamericana relat\u00f3 que los valores quedaron de la siguiente manera en la petrolera YPF:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00faper: $1204<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Infinia: $1464<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Di\u00e9sel 500: $1249<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Infinia Di\u00e9sel: 1495<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la estaci\u00f3n de servicios en la que consult\u00f3 los nuevos valores se pod\u00eda ver que en la noche de este jueves la mayor\u00eda de los conductores se hab\u00eda adelantado a la carga. Solamente hab\u00eda una moto y un auto y en casi todas las estaciones de la ciudad se repet\u00eda la imagen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>los nuevos valores que aplic\u00f3 este viernes 3 de enero la petrolera YPF en la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=897"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/897\/revisions"}],"predecessor-version":[{"id":899,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/897\/revisions\/899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/898"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}