{"id":888,"date":"2025-01-14T11:41:04","date_gmt":"2025-01-14T11:41:04","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=888"},"modified":"2025-01-14T11:41:05","modified_gmt":"2025-01-14T11:41:05","slug":"milei-cuestiono-la-custodia-estatal-de-fabiola-yanez-y-le-pidio-a-la-justicia-que-la-retire","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2025\/01\/14\/milei-cuestiono-la-custodia-estatal-de-fabiola-yanez-y-le-pidio-a-la-justicia-que-la-retire\/","title":{"rendered":"MILEI CUESTION\u00d3 LA CUSTODIA ESTATAL DE FABIOLA YA\u00d1EZ Y LE PIDI\u00d3 A LA JUSTICIA QUE LA RETIRE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La pol\u00e9mica por la seguridad de la exprimera dama resurgi\u00f3 luego de que se difundieran videos suyos cenando en Madrid por la celebraci\u00f3n de A\u00f1o Nuevo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de que se viralizara un video de la&nbsp;exprimera dama&nbsp;Fabiola Ya\u00f1ez&nbsp;cenando en&nbsp;Madrid&nbsp;en A\u00f1o Nuevo, el presidente&nbsp;Javier Milei&nbsp;cruz\u00f3 a la expareja de&nbsp;Alberto Fern\u00e1ndez&nbsp;y&nbsp;asegur\u00f3 que pedir\u00e1 un informe sobre el &#8220;sinsentido de mantener una custodia&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario anunci\u00f3 a trav\u00e9s de sus redes sociales que le pidi\u00f3 a la&nbsp;ministra de Seguridad, Patricia Bullrich, que lleve adelante la solicitud a la&nbsp;Justicia&nbsp;para cuestionar la custodia de&nbsp;Ya\u00f1ez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Seguro que la justicia evaluar\u00e1 este pedido positivamente.&nbsp;Los impuestos de los ciudadanos son para mejorar la vida de la poblaci\u00f3n. No para privilegios de quienes no llevaron con austeridad la investidura&#8221;, concluy\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e1pidamente,&nbsp;Bullrich&nbsp;respondi\u00f3 a la publicaci\u00f3n de Milei y asegur\u00f3: &#8220;Presidente:&nbsp;ya hago el informe de manera inmediata y se lo elevo a la Justicia&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Resurgi\u00f3 la pol\u00e9mica por la custodia de Fabiola Ya\u00f1ez<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La pol\u00e9mica por la custodia de&nbsp;Ya\u00f1ez&nbsp;volvi\u00f3 a surgir luego de se difundieran im\u00e1genes de la exprimera dama festejando&nbsp;A\u00f1o Nuevo en un restaurante mexicano en Madrid, donde vive actualmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La custodia estatal cuida de la primera dama en Espa\u00f1a y en agosto, luego de que presentara su denuncia por violencia de g\u00e9nero contra Alberto Fern\u00e1ndez, se sumaron dos nuevos custodios de la&nbsp;Polic\u00eda Federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La llegada de los nuevos efectivos estuvo dispuesta por la&nbsp;Justicia.&nbsp;Adem\u00e1s, hubo un recambio de personal ya que Ya\u00f1ez pidi\u00f3 no mantener el mismo personal que ten\u00eda cuando estaba en pareja con el expresidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya\u00f1ez vive en&nbsp;Espa\u00f1a desde que Fern\u00e1ndez&nbsp;termin\u00f3 su mandato como presidente. Lo denunci\u00f3 por violencia de g\u00e9nero, una causa en la que el juez federal&nbsp;Juli\u00e1n Ercolini&nbsp;cit\u00f3 a&nbsp;Fern\u00e1ndez&nbsp;a declaraci\u00f3n indagatoria el pr\u00f3ximo 4 de febrero.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Diputada libertaria present\u00f3 un proyecto para quitarle la custodia estatal a Fabiola Ya\u00f1ez<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de este hecho, la diputada de La Libertad Avanza,&nbsp;Marcela Pagano, present\u00f3 hoy un proyecto para quitarle la custodia a la ex primera dama Fabiola Ya\u00f1ez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pagano difundi\u00f3 la iniciativa en su cuenta de X: &#8220;Sobre el caso de Fabiola Y\u00e1\u00f1ez y el beneficio de estar custodiada con el bolsillo de todos los argentinos en Espa\u00f1a mientras manten\u00eda una cita amorosa,&nbsp;decid\u00ed presentar un proyecto de ley para eliminar las custodias en el exterior de ex mandatarios&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de este proyecto, Pagano busca &#8220;optimizar el gasto p\u00fablico y fortalecer la estructura de seguridad presidencial&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro de los puntos que propone el texto es limitar el tiempo que duran las custodias al llevarlo a 12 a\u00f1os y deja fuera a los familiares directos del Presidente, pero solo en el territorio argentino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su cuenta de X, Pagano dijo: &#8220;Al establecer&nbsp;l\u00edmites claros y razonables en la asignaci\u00f3n de custodias, se busca alcanzar un&nbsp;equilibrio&nbsp;adecuado entre las necesidades de protecci\u00f3n y los principios de equidad y sostenibilidad en el gasto p\u00fablico&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pol\u00e9mica por la seguridad de la exprimera dama resurgi\u00f3 luego de que se difundieran [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=888"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/888\/revisions"}],"predecessor-version":[{"id":890,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/888\/revisions\/890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/889"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}