{"id":881,"date":"2024-12-03T14:49:22","date_gmt":"2024-12-03T14:49:22","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=881"},"modified":"2024-12-03T14:49:22","modified_gmt":"2024-12-03T14:49:22","slug":"el-gobierno-posterga-la-quita-total-de-los-subsidios-a-las-tarifas-de-luz-hasta-abril-2025","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2024\/12\/03\/el-gobierno-posterga-la-quita-total-de-los-subsidios-a-las-tarifas-de-luz-hasta-abril-2025\/","title":{"rendered":"EL GOBIERNO POSTERGA LA QUITA TOTAL DE LOS SUBSIDIOS A LAS TARIFAS DE LUZ HASTA ABRIL 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Secretaria de Energ\u00eda anunci\u00f3 tambi\u00e9n que pondr\u00e1 en marcha la primera licitaci\u00f3n para la expansi\u00f3n de l\u00edneas de transporte de alta tensi\u00f3n, en un verano que se prev\u00e9 dif\u00edcil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria de Energ\u00eda, Mar\u00eda Tettamanti, anunci\u00f3 que el Gobierno est\u00e1 desarrollando un nuevo esquema de subsidios para los servicios de luz y gas, con la intenci\u00f3n de implementar un mecanismo similar a una tarifa social. Este modelo incluir\u00e1 un per\u00edodo de transici\u00f3n que se extender\u00e1 hasta abril de 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, Tettamanti adelant\u00f3 que en el transcurso del mes se lanzar\u00e1 la primera licitaci\u00f3n para poner en marcha un plan de expansi\u00f3n de las l\u00edneas de transporte de alta tensi\u00f3n. El proyecto inicial se llevar\u00e1 a cabo en el \u00c1rea Metropolitana de Buenos Aires (AMBA) y requerir\u00e1 una inversi\u00f3n estimada en 1.000 millones de d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su participaci\u00f3n en el evento Energy Day, la funcionaria explic\u00f3 que el esquema actual de segmentaci\u00f3n en categor\u00edas N1, N2 y N3 probablemente se mantendr\u00e1 en esta etapa de transici\u00f3n, pero la meta final es establecer una tarifa focalizada, similar a una tarifa social. &#8220;Queremos que haya un bloque m\u00ednimo subsidiado para las personas que lo necesiten, pero que a partir de cierto consumo se refleje el costo real de la producci\u00f3n, transporte y distribuci\u00f3n&#8221;, puntualiz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, Tettamanti destac\u00f3 la importancia de que este bloque subsidiado contemple las diferencias en las necesidades de consumo seg\u00fan las caracter\u00edsticas clim\u00e1ticas de cada regi\u00f3n del pa\u00eds. En el caso del gas natural, este criterio ya se aplica, pero todav\u00eda no se ha implementado en la energ\u00eda el\u00e9ctrica.<br>Por otro lado, inform\u00f3 que junto con Osvaldo Rolando ya se comenz\u00f3 a trabajar en la Revisi\u00f3n Tarifaria Integral (RTI) quinquenal. Aunque los avances han sido limitados, especialmente en lo referente a las tarifas de gas natural, afirm\u00f3 que este proceso es esencial. &#8220;La tarifa debe ser justa y razonable, cubrir los costos y garantizar una rentabilidad adecuada&#8221;, concluy\u00f3, dejando abierta la posibilidad de realizar esta revisi\u00f3n de manera gradual, tal como se hizo en la RTI de 2017.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando fue consultada por los tiempos para aplicar la RTI, evit\u00f3 dar fechas y precisiones. &#8220;Veremos con qu\u00e9 ritmo se puede hacer. Si se puede hacer de una sola vez o en dos o tres pasos como se hizo en la RTI de 2017. A veces uno tiene muy claro d\u00f3nde quiere llegar, pero hay que ver en qu\u00e9 tiempo. Es como si uno est\u00e1 en Buenos Aires y quiere llegar a Mar del Plata. \u00bfEn qu\u00e9 tiempo se puede llegar? \u00bfTen\u00e9s una autopista perfectamente asfaltada y ten\u00e9s un auto \u00faltimo modelo o ten\u00e9s un camino poceado con un auto que se queda cada dos por tres? Las tarifas tienen que estar determinadas por los principios de la ley. La tarifa tiene que ser justa y razonable, cubrir los costos y garantizar una rentabilidad&#8221;, sostuvo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretaria de Energ\u00eda anunci\u00f3 tambi\u00e9n que pondr\u00e1 en marcha la primera licitaci\u00f3n para la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=881"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/881\/revisions"}],"predecessor-version":[{"id":883,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/881\/revisions\/883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/882"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}