{"id":858,"date":"2024-11-20T23:21:58","date_gmt":"2024-11-20T23:21:58","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=858"},"modified":"2024-11-24T23:25:21","modified_gmt":"2024-11-24T23:25:21","slug":"la-altisima-cifra-en-dolares-que-pampita-habria-recibido-por-su-entrevista-con-susana-gimenez","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2024\/11\/20\/la-altisima-cifra-en-dolares-que-pampita-habria-recibido-por-su-entrevista-con-susana-gimenez\/","title":{"rendered":"LA ALT\u00cdSIMA CIFRA EN D\u00d3LARES QUE PAMPITA HABR\u00cdA RECIBIDO POR SU ENTREVISTA CON SUSANA GIM\u00c9NEZ"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Adri\u00e1n Pallares en Socios del Espect\u00e1culo lanz\u00f3 una versi\u00f3n sobre el monto que la producci\u00f3n habr\u00eda desembolsado por la exclusiva de la modelo hablando de Roberto Garc\u00eda Morit\u00e1n y Mart\u00edn Pepa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cifras detr\u00e1s de las exclusivas en televisi\u00f3n siempre han despertado curiosidad, y la&nbsp;reciente entrevista entre&nbsp;Pampita&nbsp;y&nbsp;Susana Gim\u00e9nez&nbsp;no fue la excepci\u00f3n. Por la nota, donde la modelo habl\u00f3 por primera vez en profundidad sobre su separaci\u00f3n de&nbsp;Roberto Garc\u00eda Morit\u00e1n&nbsp;y confirm\u00f3 que&nbsp;est\u00e1 saliendo con&nbsp;Mart\u00edn Pepa, seg\u00fan cont\u00f3 Adri\u00e1n Pallares en&nbsp;Socios del Espect\u00e1culo, la producci\u00f3n del ciclo de la diva habr\u00eda pagado una cifra de cinco cifras en d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan revel\u00f3 Pallares en el ciclo de El Trece la modelo habr\u00eda recibido 30 mil d\u00f3lares por su participaci\u00f3n. \u201cPara ella se terminaron los proyectos, el amor, pero&nbsp;lo que no se termin\u00f3 es Pampita y los negocios. Ac\u00e1 no se miente y vamos a la fuente. No tenemos muchas primicias pero cuando las tenemos son de verdad. Para estar sentada en el living de Susana Gim\u00e9nez, para evitar cartas documento y todos los enojos que pueden llegar a venir,&nbsp;habr\u00eda cobrado 30 mil d\u00f3lares por estar sentada en su programa\u201d, afirm\u00f3 el conductor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs una cifra que es un mont\u00f3n, pero dentro de todo&#8230;\u201d, consider\u00f3, para despu\u00e9s lanzar una cr\u00edtica humor\u00edstica a c\u00f3mo se desenvolvi\u00f3 la nota. \u201c\u00a1Te estafaron, Susana! Sal\u00ed corriendo y and\u00e1 a la comisar\u00eda a hacer la denuncia\u201d, coment\u00f3 con tono sarc\u00e1stico, aludiendo a las declaraciones que dio Carolina durante la entrevista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa producci\u00f3n de Susana dijo \u2018ella va a saber ir sac\u00e1ndole&#8230;\u2019, pero la frase que termin\u00f3 diciendo fue \u2018no me pod\u00e9s hacer esto\u2019. Como diciendo \u2018con lo que te pagamos\u2019\u201d, opin\u00f3 el periodista, sobre una de las expresiones que us\u00f3 la conductora al notar el hermetismo que la exjurado del Bailando eligi\u00f3 para referirse, en especial, a su escandaloso divorcio del economista como al comienzo de su v\u00ednculo amoroso con su actual pareja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Mariana Brey defendi\u00f3 a Carolina. \u201cTampoco es que no dijo nada. No cont\u00f3 en detalle la ruptura. Dijo lo suficiente como que pas\u00f3 algo como para que todo se rompa en 24 horas\u201d, se\u00f1al\u00f3 la panelista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El domingo por la noche en el ciclo de la diva, por primera vez&nbsp;Pampita se abri\u00f3 sobre sus agitados \u00faltimos meses&nbsp;que vivi\u00f3, separada del exfuncionario p\u00fablico y el comienzo unas semanas despu\u00e9s un romance con el empresario que vive en Estados Unidos.&nbsp;\u201cFue una bomba. Explot\u00f3 todo y no se pudo pegar\u201d, se sincer\u00f3 sobre su matrimonio en una nota que fue tema de toda la televisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPas\u00f3 algo que destruy\u00f3 la relaci\u00f3n. Yo viv\u00eda en un mundo donde estaba todo bien, que \u00edbamos a estar toda la vida juntos, que era para m\u00ed un proyecto so\u00f1ado\u201d, se\u00f1al\u00f3. \u201cToda la vida quise tener mi familia. Mis hijitos, un compa\u00f1ero, volver de trabajar y tener a alguien que me abrace, dormir abrazados. Siempre lo busqu\u00e9 y lo voy a seguir buscando porque esa es mi esencia. No me imagin\u00e9 que se iba a acabar, que se iba a destruir, que iba a desaparecer todo\u201d, se lament\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfLa causa fue por un enga\u00f1o? \u00bfPor plata?\u201d, le pregunt\u00f3 la animadora, insistente. \u201cPor plata, no, Su. Por Dios\u201d, contest\u00f3, mientras marcaba que todo hab\u00eda sido sorpresivo y de una forma veloz&nbsp;\u201cSe termin\u00f3 todo de un d\u00eda para el otro\u201d, afirm\u00f3, mientras soltaba enigm\u00e1ticas frases como \u201chay que tener los ojos bien abiertos\u201d y otras m\u00e1s resonantes como \u201cel que no quiere estar conmigo, la puerta est\u00e1 ah\u00ed, no le vas a rogar al otro para que se quede\u201d. \u201cYo no era la prioridad de Roberto\u201d, marc\u00f3, en otro de los momentos mientras advert\u00eda que no quer\u00eda referirse en malos t\u00e9rminos a su ex porque tanto sus hijos, como los que \u00e9l tuvo en su matrimonio anterior con Milagros Brito, estaban vi\u00e9ndola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adri\u00e1n Pallares en Socios del Espect\u00e1culo lanz\u00f3 una versi\u00f3n sobre el monto que la producci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=858"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/858\/revisions"}],"predecessor-version":[{"id":860,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/858\/revisions\/860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/859"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}