{"id":821,"date":"2024-09-27T14:48:41","date_gmt":"2024-09-27T14:48:41","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=821"},"modified":"2024-09-27T14:48:42","modified_gmt":"2024-09-27T14:48:42","slug":"dia-del-comparsero-por-que-se-celebra-este-23-de-septiembre-2","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2024\/09\/27\/dia-del-comparsero-por-que-se-celebra-este-23-de-septiembre-2\/","title":{"rendered":"D\u00cdA DEL COMPARSERO: POR QU\u00c9 SE CELEBRA ESTE 23 DE SEPTIEMBRE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El futbolista estuvo junto a su amigo Leandro Paredes en el living de la diva y tuvieron una charla muy divertida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La vuelta de&nbsp;Susana Gim\u00e9nez&nbsp;a la televisi\u00f3n cont\u00f3 con dos invitados de lujo:&nbsp;Rodrigo De Paul&nbsp;y&nbsp;Leandro Paredes<\/strong>, quienes conversaron con la diva sobre cuestiones de su vida privada y tambi\u00e9n de los grandes logros que consiguieron con la Selecci\u00f3n argentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los momentos m\u00e1s divertidos de la charla fue cuando la conductora le pregunt\u00f3 al \u201cMotorcito\u201d c\u00f3mo es en el amor. Con un poco de pudor,&nbsp;<strong>el futbolista reconoci\u00f3 que es \u201cmuy rom\u00e1ntico\u201d y dio a conocer una faceta suya desconocida<\/strong>.&nbsp;\u201c<em><strong>Me gusta mucho escribir cartas de amor<\/strong><\/em>\u201d, revel\u00f3. \u201c<em><strong>\u00a1Cartas de amor es m\u00e1s f\u00e1cil! Yo pens\u00e9 que libros<\/strong><\/em>\u201d, acot\u00f3 Su, sin creer lo que acababa de escuchar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la sorpresa que le gener\u00f3 a la anfitriona, el jugador del Atl\u00e9tico Madrid explic\u00f3:&nbsp;\u201c<em><strong>He escrito cartas de amor muy sentidas. Soy de las flores, charlas, copa de vino, introspecci\u00f3n, cenas&#8230;<\/strong><\/em>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Minutos despu\u00e9s, la diva quiso saber un poco m\u00e1s en la intimidad del futbolista y le pregunt\u00f3 si est\u00e1 en pareja.&nbsp;\u201c<strong>Estoy soltero, bien y tranquilo<\/strong>\u201d, respondi\u00f3 el ex de Tini Stoessel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El ins\u00f3lito pedido que le hizo Mar\u00eda Becerra a Susana Gim\u00e9nez en vivo: \u201cMi t\u00eda Gladys quiere conocerte\u201d<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Becerra&nbsp;fue otra de las invitadas de lujo en la vuelta de&nbsp;Susana Gim\u00e9nez&nbsp;a la televisi\u00f3n. La cantante convers\u00f3 con la diva y&nbsp;un momento inesperado de la charla no tard\u00f3 en volverse viral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em><strong>Te pido que saludes por favor a mi t\u00eda Gladys<\/strong><\/em>\u201d, le dijo la int\u00e9rprete de \u201cCoraz\u00f3n vac\u00edo\u201d a la conductora. En ese momento, ante la sorpresa de todos,&nbsp;<strong>la entrevistada convoc\u00f3 a su familiar para que ingrese al estudio y cumpla el sue\u00f1o de conocer a su \u00eddola<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con mucha buena onda, Gim\u00e9nez se fundi\u00f3 en un abrazo con Gladys y juntas recordaron algunos momentos ic\u00f3nicos de su programa.&nbsp;\u201c<strong><em>Ella te ama, por eso quer\u00eda conocerte<\/em><\/strong>\u201d, acot\u00f3 Becerra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este momento se volvi\u00f3 tendencia en las redes sociales donde los usuarios destacaron las espontaneidad de la artista y la simpat\u00eda de la conductora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em><strong>Me hicieron llorar<\/strong><\/em>\u201d,\u00a0\u201c<em><strong>\u00a1Amo que sea tan real!<\/strong><\/em>\u201d,\u00a0\u201c<em><strong>\u00a1Logr\u00f3 manguearle un saludo en vivo para la t\u00eda!<\/strong><\/em>\u201d,\u00a0\u201c<strong><em>Todos nos sentimos representados por Gladys<\/em><\/strong>\u201d,\u00a0\u201c<strong>Es incre\u00edble, es real, lo \u00fanico que le importaba era hacer feliz a la t\u00eda<\/strong>\u201d,\u00a0\u201c<strong><em>El abrazo de Susana, por algo es la n\u00famero uno<\/em><\/strong>\u201d, y\u00a0\u201c<strong><em>\u00a1Es imposible no amarla a Mar\u00eda!<\/em><\/strong>\u201d, fueron algunos de los comentarios que coparon X (ex Twitter).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-09-23\/910700.png\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El futbolista estuvo junto a su amigo Leandro Paredes en el living de la diva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=821"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/821\/revisions"}],"predecessor-version":[{"id":823,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/821\/revisions\/823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/822"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}