{"id":764,"date":"2024-07-23T07:04:16","date_gmt":"2024-07-23T07:04:16","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=764"},"modified":"2024-07-26T07:13:54","modified_gmt":"2024-07-26T07:13:54","slug":"buscan-a-loan-pena-en-chubut-y-santa-cruz-un-hombre-dice-haberlo-visto","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2024\/07\/23\/buscan-a-loan-pena-en-chubut-y-santa-cruz-un-hombre-dice-haberlo-visto\/","title":{"rendered":"BUSCAN A LOAN PE\u00d1A EN CHUBUT Y SANTA CRUZ: UN HOMBRE DICE HABERLO VISTO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un suboficial del Ej\u00e9rcito denunci\u00f3 ante las autoridades de la ciudad chubutense de Comodoro Rivadavia haberse encontrado con un ni\u00f1o en una terminal de micro, de apariencia similar al correntino, que le dijo &#8220;Soy Loan&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Gendarmer\u00eda y la Polic\u00eda de\u00a0Chubut\u00a0y\u00a0Santa Cruz\u00a0realizan\u00a0rigurosos controles en las rutas 3, 26 y 29 que atraviesan las respectivas provincias\u00a0para revisar a los autos que circulan hacia Caleta Olivia,\u00a0en el marco de una nueva pista que podr\u00eda conducir al\u00a0paradero de Loan Danilo Pe\u00f1a, el ni\u00f1o correntino desaparecido desde el 13 de junio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pasaron&nbsp;40 d\u00edas&nbsp;desde la desaparici\u00f3n del menor de 5 a\u00f1os&nbsp;tras un almuerzo familiar en el Paraje Algarrobal, en la provincia de Corrientes. Desde entonces,&nbsp;la investigaci\u00f3n estuvo atravesada por un lodazal de pistas,&nbsp;declaraciones,&nbsp;acusaciones y trascendidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este marco,&nbsp;&nbsp;un suboficial del Ej\u00e9rcito denunci\u00f3 este martes haber visto a un ni\u00f1o con similares caracter\u00edsticas a Loan junto con un hombre&nbsp;en una terminal de micro de Comodoro Rivadavia, en Chubut. La Justicia Federal lo cit\u00f3 a declarar en las pr\u00f3ximas horas.&nbsp;El suboficial a\u00f1adi\u00f3 en su denuncia que el menor le dijo&nbsp;&#8220;soy Loan&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstoy seguro de que se trata de Loan\u201d, apunt\u00f3 el integrante del Ej\u00e9rcito, de apellido Ferreyra. Seg\u00fan su relato, se encontraba esperando a su esposa en la intersecci\u00f3n de las avenidas San Mart\u00edn y Alem, una zona c\u00e9ntrica de la ciudad, en compa\u00f1\u00eda de su hijo, cuando se acerc\u00f3 otro nene y les dijo:&nbsp;\u201cYo soy Loan\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el relato del hombre, un adulto apareci\u00f3 y se llev\u00f3 al ni\u00f1o. Desde ese momento,&nbsp;el suboficial lo perdi\u00f3 de vista, y luego alert\u00f3 a las autoridades, que por el momento realiza&nbsp;controles en las rutas&nbsp;y&nbsp;analiza distintas c\u00e1maras de seguridad&nbsp;ubicadas en los accesos a la ciudad. La Gendarmer\u00eda y la Polic\u00eda local se encuentran realizando controles rigurosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la denuncia interviene el&nbsp;Juzgado Federal de Comodoro Rivadavia, a cargo de Eva Parcio De Seleme, quien dispuso que se realice un&nbsp;operativo cerrojo en la Ruta Nacional N\u00ba3 y Ruta Provincial N\u00ba 39, como as\u00ed tambi\u00e9n en la&nbsp;Ruta Nacional N\u00ba 26. Inclusive se solicit\u00f3 la colaboraci\u00f3n de todas las fuerzas de seguridad de la zona coordinadas por Polic\u00eda Federal Argentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jueza cit\u00f3 a Ferreyra, y est\u00e1 previsto que hoy declare ante la Justicia. Hasta el momento&nbsp;se logr\u00f3 establecer que en las c\u00e1maras de seguridad cercanas a la terminal se alcanza a ver a un hombre con un nene&nbsp;vestido con caracter\u00edsticas similares a las que el suboficial describi\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un suboficial del Ej\u00e9rcito denunci\u00f3 ante las autoridades de la ciudad chubutense de Comodoro Rivadavia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=764"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/764\/revisions"}],"predecessor-version":[{"id":766,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/764\/revisions\/766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/765"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}