{"id":731,"date":"2024-05-18T16:06:32","date_gmt":"2024-05-18T16:06:32","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=731"},"modified":"2024-06-18T16:47:25","modified_gmt":"2024-06-18T16:47:25","slug":"river-goleo-a-belgrano-con-el-aporte-del-diablito-echeverri","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2024\/05\/18\/river-goleo-a-belgrano-con-el-aporte-del-diablito-echeverri\/","title":{"rendered":"RIVER GOLE\u00d3 A BELGRANO CON EL APORTE DEL &#8220;DIABLITO&#8221; ECHEVERRI"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El conjunto millonario derrot\u00f3 3 a 0 al Pirata en el Monumental con los goles del chaque\u00f1o, Facundo Colidio y Pablo Solari.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por la segunda fecha de la Liga Profesional 2024, River derrot\u00f3 3-0 a Belgrano este s\u00e1bado en el Monumental. Con este resultado, el equipo de Mart\u00edn Demicehelis es moment\u00e1neamente&nbsp;l\u00edder de la tabla con puntaje ideal y sin goles en contra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la primera mitad, el Millonario tomar\u00eda la ventaja de la mano del chaque\u00f1o Claudio Echeverri a los 35 minutos, tras una mala salida del fondo del equipo celeste. A partir de all\u00ed el encuentro fue dominado por el local, que someti\u00f3 durante el resto del juego a su rival.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el segundo tiempo el partido ser\u00eda liquidado a partir del ingreso de Facundo Colidio quien a los 36 minutos pondr\u00eda el 2-0 parcial ante la estirada del arquero Nahuel Losada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, Pablo Solari decretar\u00eda el 3-0 final tras un desborde de Ignacio Fern\u00e1ndez. Con este resultado, los de Nu\u00f1ez cosecharon su segunda victoria en el torneo y con el mismo resultado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pr\u00f3xima fecha, River visitar\u00e1 a Argentinos Juniors en Paternal, mientras que Belgrano recibir\u00e1 a Central C\u00f3rdoba como local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El conjunto millonario derrot\u00f3 3 a 0 al Pirata en el Monumental con los goles [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=731"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/731\/revisions"}],"predecessor-version":[{"id":733,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/731\/revisions\/733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/732"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}