{"id":710,"date":"2024-04-14T13:37:12","date_gmt":"2024-04-14T13:37:12","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=710"},"modified":"2024-04-24T13:38:15","modified_gmt":"2024-04-24T13:38:15","slug":"el-escaneo-de-iris-habria-llegado-a-esquina-y-dejo-30-000-por-persona","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2024\/04\/14\/el-escaneo-de-iris-habria-llegado-a-esquina-y-dejo-30-000-por-persona\/","title":{"rendered":"EL ESCANEO DE IRIS HABR\u00cdA LLEGADO A ESQUINA Y DEJ\u00d3 $30.000 POR PERSONA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un sitio informativo de la ciudad dio cuenta de largas filas para acceder a lo que ser\u00eda un operativo de rastreo de ojos. Se trata de una modalidad llevada a cabo en Argentina por una empresa de criptomonedas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los famosos escaneos de ojos a cambio de dinero habr\u00edan llegado al sur de la provincia. Un portal informativo de Esquina revel\u00f3 un operativo que reuni\u00f3 a unas 300 personas entre el lunes y viernes de la semana pasada. No descartan que se haya tratado de una estafa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El punto de encuentro fue una casa alquilada ubicada sobre Moreno, entre Constituci\u00f3n y Genaro Rebechi, donde decenas de personas habr\u00edan llegado con la intenci\u00f3n de vender sus datos biom\u00e9tricos a cambio de unas criptomonedas intercambiables por dinero en efectivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La postal registrada por actualidadesquina.com fue id\u00e9ntica a la vista en otros puntos del pa\u00eds: largas filas de personas, generalmente de bajos recursos econ\u00f3micos, esperando al aire libre y sin ninguna intenci\u00f3n de hablar con los medios de comunicaci\u00f3n. Es que la empresa que realiza los escaneos de iris solicita a los interesados absoluta confidencialidad durante el proceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La firma internacional que estar\u00eda a cargo de estos operativos ser\u00eda Worldcoin, cuyo propietario es Sam Altman, creador de la inteligencia artificial ChatGPT. Los datos que recaban ser\u00edan utilizados como herramienta para garantizar la seguridad y la confiabilidad de las transacciones de las criptos de la empresa. En s\u00edntesis, la idea es garantizar que el usuario interviniente sea una persona y no un bot (robot), Un hecho que no deja en claro porque se paga una importante suma de dinero a quienes acceden al escaneo de los ojos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada iris posee 256 puntos caracter\u00edsticos que nos convierten en individuos irrepetibles. De esta forma se garantiza la identidad a\u00fan m\u00e1s que las huellas digitales, que cuentan con 40 patrones personales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La producci\u00f3n se comunic\u00f3 con una fuente de Worldcoin y confirmaron que no hab\u00eda ning\u00fan punto habilitado en Esquina. Por ello creemos que la gente vendi\u00f3 su identidad a desconocidos que pueden usar su datos para solicitar un cr\u00e9dito o realizar otras estafas&#8221;, coment\u00f3, en una entrevista con diario \u00e9poca, Eduardo Schweizer, propietario del portal de noticias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de grupos de WhatsApp de la localidad, se conoci\u00f3 que la convocatoria se realiz\u00f3 por Facebook. Y a los interesados se les ped\u00eda un correo electr\u00f3nico y un n\u00famero de celular. &#8220;Creemos que la mayor\u00eda de la gente que asisti\u00f3 no baj\u00f3 la aplicaci\u00f3n necesaria para recibir las criptomonedas, por lo que es por dem\u00e1s sospechoso&#8221;, acot\u00f3. Lo \u00fanico confirmado es que cada uno necesit\u00f3 tramitar un turno para asistir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Worldcoin desembarc\u00f3 en Buenos Aires a finales de 2022 y se hizo conocida por sus puestos en la costa. Adem\u00e1s de Pinamar, el grupo de promotores con el ORB (aparato que toma los datos) tambi\u00e9n estuvo en Villa Gesell y Mar del Plata. Cuando se googlea el nombre de la compa\u00f1\u00eda aparecen art\u00edculos period\u00edsticos de los pa\u00edses en los que opera en los que se advierte sobre la pol\u00e9mica recolecci\u00f3n de datos biom\u00e9tricos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se calcula que en Argentina m\u00e1s de 360.000 personas ya llevaron a cabo este proceso que gener\u00f3 concentraciones y extensas colas en centros comerciales, plazas, boliches y grandes centros, principalmente en el conurbano. Sin embargo, nadie a ciencia cierta pueda dar fe que Worldcoin fue la que estuvo en Esquina la semana pasada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un sitio informativo de la ciudad dio cuenta de largas filas para acceder a lo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=710"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/710\/revisions"}],"predecessor-version":[{"id":712,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/710\/revisions\/712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/711"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}