{"id":707,"date":"2024-04-14T13:34:39","date_gmt":"2024-04-14T13:34:39","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=707"},"modified":"2024-04-24T13:38:21","modified_gmt":"2024-04-24T13:38:21","slug":"vacuna-contra-el-dengue-el-50-de-los-inscriptos-no-cumple-los-requisitos","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2024\/04\/14\/vacuna-contra-el-dengue-el-50-de-los-inscriptos-no-cumple-los-requisitos\/","title":{"rendered":"VACUNA CONTRA EL DENGUE: EL 50% DE LOS INSCRIPTOS NO CUMPLE LOS REQUISITOS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Desde la SUSTI informaron que solamente ocho mil inscriptos registrados cumplimentaban los par\u00e1metros solicitados para recibir la inoculaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vacuna contra el dengue empez\u00f3 a aplicarse a mediados de la semana pasada en Capital en el Hospital Escuela, Hospital Llano, Hospital de Campa\u00f1a y el CAPS N\u00ba1 del barrio San Jos\u00e9; como as\u00ed tambi\u00e9n en seis localidades del interior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para conocer m\u00e1s sobre quienes se pueden inscribir y cu\u00e1ntos ya lo hicieron, \u00e9poca dialog\u00f3 con el subsecretario de Sistemas y Tecnolog\u00edas de Informaci\u00f3n (SUSTI), Federico Ojeda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Son 16.000 las personas inscriptas hasta el momento&#8221;, remarc\u00f3 Ojeda. Al ser consultado sobre si encontraron irregularidades en las inscripciones dej\u00f3 en claro que &#8220;no lo hicimos. Lo que pasa es que tenemos tres tipos de requisitos, que son la edad de 20-40, que tenga domicilio en los municipios en los que se lanz\u00f3 la vacuna y adem\u00e1s de eso, el otro requisito es que la prioridad, en este caso, la tienen las personas sin obra social&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso quiere decir que alrededor de esos 16.000, ocho mil cumplen los requisitos para recibir los turnos, lo que nos deja un porcentaje del 50% los que no podr\u00e1n recibir la vacuna por no estar enmarcados en esos criterios de vacunaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe recordar que tambi\u00e9n se est\u00e1 inoculando en el interior, por ello para conocer m\u00e1s sobre la distribuci\u00f3n de los vacunados y cu\u00e1ntos se inscribieron en el interior; el Subsecretario resalt\u00f3 que &#8220;de esos 16.000, Capital nuclea el 80% del total de inscripciones y el 20 por ciento restante se distribuye en el interior&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ojeda asever\u00f3 que en las seis localidades del interior &#8220;est\u00e1 bastante distribuido, son alrededor de 500 inscriptos por localidad en las m\u00e1s chicas, y la que m\u00e1s inscriptos tiene en el interior es Bella Vista, con casi 1.000&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n brind\u00f3 detalles de las localidades en las que sus habitantes con residencia en ellas, que cumplan los requisitos, se pueden inscribir: &#8220;Capital, Gobernador Virasoro, Paso de la Patria, San Luis del Palmar, Bella Vista, Santo Tom\u00e9 e Ituzaing\u00f3, son los municipios que est\u00e1n habilitados para los turnos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Detr\u00e1s de Capital, con el 80% de las inscripciones, por la cantidad de poblaci\u00f3n, est\u00e1 Bella Vista; luego Santo Tom\u00e9 y San Luis del Palmar&#8221;, asever\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ser consultado si las personas tuvieron problemas a la hora de cargar sus datos en la p\u00e1gina, destac\u00f3 que &#8220;no tuvieron ning\u00fan tipo de inconvenientes, el sistema funciona perfecto y est\u00e1 directamente en la nube, quiere decir que no depende de ning\u00fan servidor f\u00edsico, y eso asegura que funcione las 24 horas ya que est\u00e1 en alta disponibilidad&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s dej\u00f3 un p\u00e1rrafo aparte para las estafas virtuales, &#8220;en lo \u00fanico en que hacemos mucho hincapi\u00e9 es en la seguridad, no compartir los datos. Una vez que el turno es asignado les va a llegar un mensaje de WhatsApp o mail avis\u00e1ndole que tienen fecha de aplicaci\u00f3n y desde ese momento pueden ir a la plataforma a verificar&#8221;, asever\u00f3 Federico Ojeda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n dijo que le dan mucha importancia a esto &#8220;porque estamos recibiendo alertas de que est\u00e1n llamando por tel\u00e9fono de n\u00fameros de Buenos Aires avisando que tienen un turno asignado, luego le piden c\u00f3digos y eso es para robarles el WhatsApp y realizar estafas virtuales&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a esto, Federico Ojeda enfatiz\u00f3 a \u00e9poca que &#8220;en ning\u00fan momento la Provincia les va a pedir un c\u00f3digo, no los va a llamar por tel\u00e9fono, no hay personas inscribiendo, todo es por la plataforma virtual y el aviso de que le dieron un turno les va a llegar al WhatsApp, que le solicita que vuelvan a la plataforma para que pongan el c\u00f3digo y ah\u00ed descargar el turno&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La gente no debe pasar ning\u00fan c\u00f3digo por el WhatsApp, no les va a llamar la Provincia por tel\u00e9fono de ninguna manera, ni les vas a mandar un mensaje&#8221;, remarc\u00f3 el Subsecretario, &#8220;no les va a hablar una persona, ya que todo es autom\u00e1tico y al recibir el turno les llega un mensaje de WhatsApp que les avisa la fecha asignada. Luego deber\u00e1n ir a la plataforma www.vacunacion,corrientes.gob.ar y ah\u00ed ponen su c\u00f3digo. No se mandan contrase\u00f1as por WhatsApp&#8221;, volvi\u00f3 a remarcar para evitar problemas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n dej\u00f3 en claro la gratuidad de la vacuna al resaltar que &#8220;es absolutamente libre y gratuita, no se cobra nada, ya que esto es una inversi\u00f3n de la provincia de Corrientes para los correntinos.Hay que tener much\u00edsimo cuidado en esa cuesti\u00f3n de dar c\u00f3digos y atender llamadas que dicen ser del Ministerio de Salud de la Naci\u00f3n como de la Provincia&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s remarc\u00f3 que solamente hay un n\u00famero habilitado para la llegada del mensaje que &#8220;es el 3794 -556055, es el \u00fanico n\u00famero que usa el Gobierno de la Provincia de Corrientes para avisar sobre el turno de la vacunaci\u00f3n. Desde esa l\u00ednea jam\u00e1s se les va a pedir un c\u00f3digo, ninguna contrase\u00f1a, ni foto del DNI, solamente se les env\u00eda un n\u00famero que les va a avisar que tienen un turno y deben ir a la p\u00e1gina a verificarlo&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n hay personas que se inscriben que no est\u00e1n en ese rango etario o no cumplen con los requisitos, a lo que Ojeda asever\u00f3 que &#8220;en la p\u00e1gina se inscriben todas las personas de 20-40 a\u00f1os que tengan domicilio en esos siete municipios y que no cuenten con obra social, los dem\u00e1s se pueden inscribir, pero no les van a dar el turno porque todav\u00eda no est\u00e1 previsto para aquellas personas que tengan obra social&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente resalt\u00f3 que &#8220;hoy la prioridad de esas vacunas son para las personas que no tienen cobertura social, depender\u00e1 del Ministerio de Salud y los criterios epidemiol\u00f3gicos abrir o no para aquellas que s\u00ed las tengan&#8221;. Por \u00faltimo, coment\u00f3 que en la SUSTI &#8220;est\u00e1n trabajando alrededor de 15 j\u00f3venes, todos de la provincia, ingenieros y licenciados en sistemas, todos Sub-25, y esta plataforma fue hecha por correntinos&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la SUSTI informaron que solamente ocho mil inscriptos registrados cumplimentaban los par\u00e1metros solicitados para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=707"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/707\/revisions"}],"predecessor-version":[{"id":709,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/707\/revisions\/709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/708"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}