{"id":654,"date":"2024-01-05T11:33:31","date_gmt":"2024-01-05T11:33:31","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=654"},"modified":"2024-01-05T11:33:32","modified_gmt":"2024-01-05T11:33:32","slug":"detuvieron-a-presunto-autor-de-golpear-a-abuela-en-un-robo","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2024\/01\/05\/detuvieron-a-presunto-autor-de-golpear-a-abuela-en-un-robo\/","title":{"rendered":"DETUVIERON A PRESUNTO AUTOR DE GOLPEAR A ABUELA EN UN ROBO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La captura del sospechoso fue en Caseros, en horas de la noche, cuando descansaba en un garaje. Tiene 51 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la localidad correntina de Monte Caseros, las tareas investigativas llevaron a concretar un allanamiento para detener al presunto autor de una brutal paliza que recibi\u00f3 una abuela durante un robo. La mujer contin\u00faa hospitalizada en un sanatorio privado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una mujer de 87 a\u00f1os de apellido Astarloa Peroni, el pasado 1 de enero en momentos que descansaba en su casa ubicada por calle Eva Duarte al 1200 de la ciudad montecasere\u00f1a, fue interceptada por al menos un delincuente, quien la golpe\u00f3 en busca de dinero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al no poder conseguir el bot\u00edn sustrajo algunas pertenencias, dej\u00e1ndola malherida en el suelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando un familiar fue a visitarla la encontr\u00f3 inconsciente y con claras muestras de una brutal golpiza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde entonces la Polic\u00eda, junto con la fiscal\u00eda, inici\u00f3 tareas investigativas para dar con \u00e9l o los presuntos autores. As\u00ed, tras an\u00e1lisis de filmaciones de c\u00e1maras de seguridad de la zona lograron identificar a uno de ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Se trat\u00f3 de un hombre conocido con el alias &#8220;Mandarina&#8221; de 51 a\u00f1os con antecedentes por robo. Al parecer, seg\u00fan algunos testimonios, es oriundo de Santo Tom\u00e9 y hace tiempo est\u00e1 en situaci\u00f3n de calle; tiene pr\u00e1cticas de consumo problem\u00e1tico de alcohol&#8221;, dijo una fuente oficial a la prensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hombre, finalmente -tras ser localizado en un garaje donde una familia lo deja dormir-, fue detenido y trasladado a la comisar\u00eda Primera. El operativo se concret\u00f3 en un inmueble ubicado sobre calle El Maestro entre Juan Pujol y San Mart\u00edn. Se inform\u00f3 que alias &#8220;Mandarina&#8221; fue imputado por el delito de &#8220;Supuesto robo y Lesiones&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale se\u00f1alar que el aporte de testimonios y material f\u00edlmico brindados por el sistema de c\u00e1maras de seguridad fue consolidando la informaci\u00f3n que apuntaba hacia el delincuente que fue atrapado por la Polic\u00eda cerca de las 21 del mi\u00e9rcoles \u00faltimo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Penas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El delito de robo simple tiene una pena prevista de entre 1 mes y 6 a\u00f1os de prisi\u00f3n o reclusi\u00f3n, seg\u00fan el art\u00edculo 164 del C\u00f3digo Penal. Mientras que la figura de lesiones prev\u00e9 penas de 1 a 6 a\u00f1os de prisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal como se inform\u00f3 en este medio, la mujer de 87 a\u00f1os present\u00f3 sutura en el cuero cabelludo y severos golpes en el rostro. Fue internada en el \u00e1rea de terapia intensiva de un sanatorio privado desde donde se inform\u00f3 a la prensa que evoluciona favorablemente y al cierre de esta edici\u00f3n informaron que est\u00e1 &#8220;fuera de peligro&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los antecedentes de &#8220;Mandarina&#8221; en base de datos result\u00f3 que, en marzo de 2013, fue acusado de &#8220;supuesto robo, amenazas, violaci\u00f3n de domicilio, abuso sexual con acceso carnal en grado de tentativa&#8221;, ocurrido en la ciudad montecasere\u00f1a. Y durante el 2023 tuvo ingresos a la comisar\u00eda por disturbios en la v\u00eda p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La captura del sospechoso fue en Caseros, en horas de la noche, cuando descansaba en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=654"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/654\/revisions"}],"predecessor-version":[{"id":656,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/654\/revisions\/656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/655"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}