{"id":605,"date":"2023-10-31T04:03:43","date_gmt":"2023-10-31T04:03:43","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=605"},"modified":"2023-10-31T04:03:44","modified_gmt":"2023-10-31T04:03:44","slug":"el-cable-e-internet-anunciaron-una-suba-del-20-para-diciembre","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2023\/10\/31\/el-cable-e-internet-anunciaron-una-suba-del-20-para-diciembre\/","title":{"rendered":"EL CABLE E INTERNET ANUNCIARON UNA SUBA DEL 20% PARA DICIEMBRE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las modificaciones en las facturan no encuentran techo y ya acumulan m\u00e1s de un 80% desde mitad de a\u00f1o. Adem\u00e1s, las firmas aplicar\u00e1n en noviembre un incremento del 15% y hay absoluta incertidumbre por lo que pasar\u00e1 despu\u00e9s del 31 de diciembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las principales prestadoras de televisi\u00f3n por cable, telefon\u00eda para el hogar e internet anunciaron aumentos de hasta un 19% para las facturas de diciembre. En tanto, para noviembre, las boletas llegar\u00e1n con subas del 15% y desde junio acumulan m\u00e1s de un 80% de incrementos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las dos empresas con m\u00e1s cobertura territorial en la ciudad de Corrientes informaron las modificaciones en el cuadro tarifario esta semana con las primeras facturaciones para el mes venidero. &#8220;Se incrementar\u00e1n los precios de los servicios de televisi\u00f3n y packs, internet en el hogar, telefon\u00eda fija nacional, adicionales y otros cargos hasta un 19%&#8221;, anunci\u00f3 en las boletas de este mes Personal Flow (antes Cablevisi\u00f3n). En tanto, Gigared SA hizo lo propio: &#8220;A partir del 1 de diciembre los precios de TV e internet subir\u00e1n hasta un 19%&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta forma, los servicios de TV, internet domiciliario y cable acumulan un aumento de 62% en los \u00faltimos seis meses que llegar\u00e1 a un 81% en diciembre, seg\u00fan un seguimiento que lleva adelante diario \u00e9poca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale recordar que el Gobierno nacional autoriz\u00f3 aumentos solo del 4,5% desde el primer d\u00eda de cada mes posterior a mayo de 2023, sucesivamente, y hasta diciembre, inclusive. Estos incrementos se iban a aplicar de acuerdo al precio anterior de cada factura. Sin embargo, se evidencia que los montos fueron superados ampliamente y van camino a completar un 70% para fin de a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la Asociaci\u00f3n de Usuarios y Consumidores de Corrientes aseguraron que, junto a asociaciones de todas las provincias, llevaron planteos a ENACOM, pero hasta la fecha ninguno tuvo respuesta<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las modificaciones en las facturan no encuentran techo y ya acumulan m\u00e1s de un 80% [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=605"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/605\/revisions"}],"predecessor-version":[{"id":607,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/605\/revisions\/607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/606"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}