{"id":513,"date":"2023-06-28T12:30:53","date_gmt":"2023-06-28T12:30:53","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=513"},"modified":"2023-06-28T12:30:53","modified_gmt":"2023-06-28T12:30:53","slug":"silvina-luna-debio-ser-internada-en-terapia-intensiva-esta-sedada-y-con-respirador","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2023\/06\/28\/silvina-luna-debio-ser-internada-en-terapia-intensiva-esta-sedada-y-con-respirador\/","title":{"rendered":"SILVINA LUNA DEBI\u00d3 SER INTERNADA EN TERAPIA INTENSIVA: &#8220;EST\u00c1 SEDADA Y CON RESPIRADOR&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La noticia fue dada a conocer por \u00c1ngel de Brito en LAM, quien adem\u00e1s dijo que la modelo permanece sedada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La salud de Silvina Luna se fue deteriorando desde que se someti\u00f3 a una intervenci\u00f3n est\u00e9tica en el 2011 a cargo del m\u00e9dico An\u00edbal Lotocki.<\/strong>&nbsp;En ese momento, la modelo hab\u00eda confiado en el especialista para&nbsp;<strong>que le inyecte biopol\u00edmeros en sus gl\u00fateos y este procedimiento le produjo una hipercalcemia y una insuficiencia renal en su organismo.<\/strong>&nbsp;Por este hecho, Lotocki fue condenado por el Tribunal Oral y Correccional N\u00b028 de la Ciudad de Buenos Aires a cuatro a\u00f1os de prisi\u00f3n (y 5 de inhabilitaci\u00f3n para ejercer la medicina) por el delito de lesiones graves en una causa que le inici\u00f3 de manera conjunta Silvina con Stefy Xipolitakis, Gabriela Trenchi y Pamela Sosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La situaci\u00f3n de Silvina es tan delicada que necesita hacerse di\u00e1lisis tres veces por semana durante cuatro horas cada vez para poder filtrar la sangre<\/strong>, ya que sus ri\u00f1ones no lo pueden hacer porque han dejado de funcionar. En este estado, la \u00fanica soluci\u00f3n para que la modelo pueda volver a tener una vida normal es recibir un trasplante de ri\u00f1\u00f3n. As\u00ed las cosas, este martes por la noche casi sobre el cierre de LAM (Am\u00e9rica) \u00c1ngel de Brito cont\u00f3 que la modelo est\u00e1 internada en terapia intensiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Lamentablemente, y lo chequeamos con sus m\u00e9dicos y con la gente del hospital Italiano, Silvina Luna est\u00e1 internada en terapia intensiva, est\u00e1 sedada y est\u00e1 con respirador. Est\u00e1 acompa\u00f1ada por su hermano y la gente que la quiere&#8221;, dijo el conductor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;No queremos hacer mucho show con este tema, solo comentarlo porque la estuvimos llamando justo en estos d\u00edas. Ella vino hace un mes al programa a contar todo lo que le hab\u00eda pasado con su salud, el tratamiento, la di\u00e1lisis y todo lo que cont\u00f3. Y finalmente, hoy pas\u00f3 a terapia intensiva&#8221;, agreg\u00f3 De Brito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal como dijo el conductor de LAM, la propia Silvina cont\u00f3 en ese programa cu\u00e1l es la situaci\u00f3n que est\u00e1 atravesando con su salud. &#8220;Para entrar en la lista de espera para un trasplante, antes tengo que vencer una bacteria que est\u00e1 dando vueltas por mi cuerpo. Tengo que pensarlo como un paso a paso&#8230; Si pienso en todo lo que tengo que encarar, me agarra una ansiedad b\u00e1rbara&#8221;, cont\u00f3 a principios de junio. Y hab\u00eda agregado: &#8220;Familiares m\u00edos se ofrecieron a donarme un ri\u00f1\u00f3n. Todav\u00eda falta y no me quiero adelantar. Primero tengo que estar en la lista del Incucai. Una de las personas que se ofreci\u00f3 fue mi hermano, pero a m\u00ed todav\u00eda me da cosa hablarlo. Yo s\u00e9 que \u00e9l est\u00e1 ah\u00ed, pero todo depende de muchas cosas&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De ese modo, Silvina relat\u00f3 en primera persona su estado real de salud mientras permanece hospitalizada haciendo los tratamientos necesarios para conseguir estabilizar los valores de su cuerpo. D\u00edas despu\u00e9s, la modelo subi\u00f3 un video grabado por ella desde la habitaci\u00f3n de la cl\u00ednica en la que permanece internada para enviar un emotivo mensaje y pedir un deseo muy especial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Hola, \u00bfc\u00f3mo est\u00e1n?. Bueno, est\u00e1n por hacerme una sedaci\u00f3n. Me van a hacer un pic en el brazo para poder recibir la medicaci\u00f3n intravenosa, me van a reponer uno que se me sali\u00f3, miren el moretonazo que me qued\u00f3 ah\u00ed&#8221;, comenz\u00f3 relatando la exparticipante de Gran Hermano mientras mostraba a la c\u00e1mara un hematoma que abarcaba todo su antebrazo izquierdo, de un color violeta intenso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Pero bueno, ahora me van a hacer otro para que resista un par de meses para poder pasar la medicaci\u00f3n por ah\u00ed. Despu\u00e9s, de este lado tengo otro pic, que es para hacer la di\u00e1lisis, que est\u00e1 ac\u00e1 abajo de la axila. Bueno, quer\u00eda saludarlos antes de entrar ac\u00e1 al quir\u00f3fano y que me deseen mucha suerte&#8221;, se despidi\u00f3 arrojando un beso con la mano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La noticia fue dada a conocer por \u00c1ngel de Brito en LAM, quien adem\u00e1s dijo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=513"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/513\/revisions"}],"predecessor-version":[{"id":515,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/513\/revisions\/515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/514"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}