{"id":451,"date":"2023-03-22T13:39:10","date_gmt":"2023-03-22T13:39:10","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=451"},"modified":"2023-03-22T13:39:10","modified_gmt":"2023-03-22T13:39:10","slug":"detuvieron-al-presunto-autor-del-ataque-a-abuela-en-intento-de-robo","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2023\/03\/22\/detuvieron-al-presunto-autor-del-ataque-a-abuela-en-intento-de-robo\/","title":{"rendered":"DETUVIERON AL PRESUNTO AUTOR DEL ATAQUE A ABUELA EN INTENTO DE ROBO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Es oriundo de Buenos Aires. Estaba de visita en Curuz\u00fa en casa de familiares. Habr\u00eda actuado junto a c\u00f3mplices.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la comisar\u00eda Primera de la localidad de Curuz\u00fa Cuati\u00e1 fue trasladado un hombre quien estar\u00eda vinculado al intento de robo y golpiza que padeci\u00f3 una abuela en zona rural de la localidad de Cazadores Correntinos el pasado 2 de marzo. El sospechoso habr\u00eda actuado junto a otros dos c\u00f3mplices.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mujer contin\u00faa recuper\u00e1ndose de las lesiones que sufri\u00f3 en el hecho denunciado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el poblado de Cazadores Correntinos, ubicado en el departamento de Curuz\u00fa Cuati\u00e1, una mujer de 80 a\u00f1os denunci\u00f3 el robo que soport\u00f3 en la casa donde vive, en el Paraje Garay, hace una semana atr\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con datos aportados por parte de la mujer, la fuerza policial inici\u00f3 de oficio la causa por supuesto robo en grado de tentativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diversas diligencias llevaron a concretar allanamientos siendo uno de ellos positivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed uniformados de la comisar\u00eda Primera de Curuz\u00fa Cuati\u00e1 y de la Brigada de Investigaciones cumplimentaron el martes, con una orden del juez de Garant\u00edas de la ciudad, la detenci\u00f3n de un hombre sindicado como principal sospechoso en el violento ataque a una abuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan las pesquisas habr\u00edan participado al menos tres sujetos y a ra\u00edz de los datos que la v\u00edctima pudo aportar a la Polic\u00eda, comenz\u00f3 una investigaci\u00f3n que termin\u00f3 con un procedimiento positivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;El detenido, mayor de edad, est\u00e1 domiciliado en la provincia de Buenos Aires, pero estaba de visita en nuestra ciudad (Curuz\u00fa Cuati\u00e1) en casa de unos familiares, en zona centro&#8221;, asegur\u00f3 una fuente oficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras ser aprehendido fue trasladado a la Secci\u00f3n Alcald\u00eda de la comisar\u00eda Primera en la que qued\u00f3 a disposici\u00f3n de la Justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Se espera que en las pr\u00f3ximas horas compadezca al juzgado, en el cual se prosiguen con las actuaciones de rigor. El procedimiento se realiz\u00f3 en un domicilio ubicado en inmediaciones a plaza General Paz&#8221;, agreg\u00f3 a este medio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El hecho<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tal como se inform\u00f3 en este matutino, hace una semana atr\u00e1s, la denunciante, una mujer de 80 a\u00f1os, cont\u00f3 a la Polic\u00eda y personal de salud que la atendi\u00f3 que en su casa, ubicada en el Paraje Garay, en Cazadores Correntinos, al menos dos personas a cara descubierta ingresaron con fines delictivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Para trabajar mejor&#8221; la maniataron, golpearon y le habr\u00edan robado varios elementos de valor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al parecer los delincuentes ten\u00edan el dato que la mujer guardaba una suma importante de dinero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un vecino de la zona fue quien observ\u00f3 movimientos extra\u00f1os en su vivienda por lo que decidi\u00f3 llegar al lugar. As\u00ed fue que la encontr\u00f3 a la mujer malherida y maniatada. Los sospechosos para entonces hab\u00edan logrado fugarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La abuela fue llevada al centro de salud de Cazadores Correntinos pero por la gravedad de sus lesiones fue trasladada luego al Hospital Civil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es oriundo de Buenos Aires. Estaba de visita en Curuz\u00fa en casa de familiares. Habr\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=451"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/451\/revisions"}],"predecessor-version":[{"id":453,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/451\/revisions\/453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/452"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}