{"id":418,"date":"2023-02-08T13:27:59","date_gmt":"2023-02-08T13:27:59","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=418"},"modified":"2023-02-08T13:27:59","modified_gmt":"2023-02-08T13:27:59","slug":"fueron-a-hacer-un-negocio-discutieron-y-uno-termino-muerto","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2023\/02\/08\/fueron-a-hacer-un-negocio-discutieron-y-uno-termino-muerto\/","title":{"rendered":"FUERON A HACER UN NEGOCIO, DISCUTIERON Y UNO TERMIN\u00d3 MUERTO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un hombre fue detenido tras acercarse a la Comisar\u00eda de Ituzaing\u00f3 a declarar por un homicidio que ocurri\u00f3 en la localidad de Santo Tom\u00e9. La muerte se produjo en una propiedad de esa ciudad y el fallecido ten\u00eda lesiones de arma blanca. Sospechan que un negocio sali\u00f3 mal. \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Polic\u00eda de Corrientes intervino en un homicidio ocurrido en la tarde de este martes, en la localidad de Santo Tom\u00e9, en una casa de calle Mitre al 100. Fue despu\u00e9s de que aparentemente dos personas discutieran por un negocio que fueron a realizar a esa ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por datos aportados a la Polic\u00eda, se supo que el fallecido, de apellido Valverdi, ten\u00eda domicilio en la localidad de Riachuelo. Habr\u00eda viajado con el supuesto agresor, de apellido Vallejos, a la mencionada localidad. Aparentemente, habr\u00edan discutido en la casa de Mitre al 100 y el atacante se retir\u00f3 con signos de agresi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Horas m\u00e1s tarde, se present\u00f3 en una Comisar\u00eda de la localidad de Ituzaing\u00f3, donde cont\u00f3 lo sucedido y qued\u00f3 detenido. Polic\u00edas e integrantes de la Fiscal\u00eda llegaron a la casa donde sucedi\u00f3 el altercado y encontraron el cuerpo sin vida de Valverdi, con lesiones de arma blanca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este fallecimiento, Corrientes registra cuatro homicidios en lo que va de 2023, todos ocurridos en el interior provincial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre fue detenido tras acercarse a la Comisar\u00eda de Ituzaing\u00f3 a declarar por un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":419,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=418"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/418\/revisions"}],"predecessor-version":[{"id":420,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/418\/revisions\/420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/419"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}