{"id":368,"date":"2022-12-16T14:12:18","date_gmt":"2022-12-16T14:12:18","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=368"},"modified":"2022-12-16T14:12:57","modified_gmt":"2022-12-16T14:12:57","slug":"el-domingo-blindaran-la-costanera-para-la-final-de-la-copa-del-mundo","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2022\/12\/16\/el-domingo-blindaran-la-costanera-para-la-final-de-la-copa-del-mundo\/","title":{"rendered":"EL DOMINGO BLINDAR\u00c1N LA COSTANERA PARA LA FINAL DE LA COPA DEL MUNDO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El amplio operativo contar\u00e1 con 130 efectivos policiales, acompa\u00f1ados de grupos especiales, m\u00f3viles, motocicletas y hasta un autobomba. La organizaci\u00f3n rompe la c\u00e1bala y traslada la Fan Fest a la bajada del puente &#8220;General Belgrano&#8221;, donde no nos fue muy bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ciudad de Corrientes, al igual que toda la provincia y el pa\u00eds, vivir\u00e1 una jornada de domingo con muchas expectativas y emociones ya que la selecci\u00f3n argentina volver\u00e1 a disputar una nueva final del campeonato mundial que se desarrolla en Qatar, instancia a la que llega por sexta vez en su historia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello, en nuestra ciudad, como en la mayor\u00eda de las capitales de Argentina, se van a desarrollar los tradicionales Fan Fest que albergar\u00e1n a los hinchas delante de pantallas gigantes colocadas para alimentar la ilusi\u00f3n de todos los argentinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan pudo averiguar \u00e9poca, con un total de 130 efectivos, la Polic\u00eda de la Provincia de Corrientes desplegar\u00e1 un importante operativo de seguridad para evitar todo tipo de desmanes que puedan ocurrir en la costanera en la jornada de domingo cuando se dispute la final de la Copa del Mundo Qatar 2022 entre Argentina y Francia, lugar en el que se espera que se concentre la mayor\u00eda de las personas posterior al cierre de la competencia mundialista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para esta ocasi\u00f3n especial, la Polic\u00eda de Corrientes dise\u00f1\u00f3 un operativo de seguridad especial para mantener el orden en la Fan Fest que tendr\u00e1 lugar, para aquellos que creen mucho en las c\u00e1balas y son de respetar sus lugares a la hora de ver los partidos, en la explanada del puente &#8220;General Belgrano&#8221;, &#8211; donde se vio el \u00fanico partido en el que cay\u00f3 derrotada en la fase de grupos- rompiendo la c\u00e1bala de ver los juegos en plena playa Arazaty, donde la selecci\u00f3n argentina no perdi\u00f3 en ninguna de sus presentaciones para llegar a esta instancia final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal vez ser\u00e1 para un mejor manejo organizativo, pero c\u00f3mo les hacen entender esto a los cabuleros quienes ya salieron al cruce de este &#8220;cambio estrat\u00e9gico&#8221; que migrar\u00e1 a la Fan Fest al lugar en que estuvo cuando se disput\u00f3 el partido de apertura ante Arabia Saudita, que perdi\u00f3 por 2 a 1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por tal efecto, el dicho &#8220;nulo mufa&#8221; estar\u00e1 muy acompa\u00f1ado por esta decisi\u00f3n poco agradable para los fan\u00e1ticos de trasladar la Fan Fest a un lugar donde, los hinchas, creen que no le fue para nada bien a nuestra selecci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Amplio operativo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En simult\u00e1neo, el amplio operativo de la Polic\u00eda de Corrientes, tambi\u00e9n montar\u00e1 un despliegue preventivo en cada localidad y ciudad del interior correntino, con motivo a la final del Mundial de Qatar que disputar\u00e1 la selecci\u00f3n argentina de f\u00fatbol este domingo desde el mediod\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al \u00e1rea Capital, fueron asignados 129 efectivos los que estar\u00e1n abocados al operativo, tambi\u00e9n contar\u00e1n con 9 m\u00f3viles policiales, acompa\u00f1ados de 9 motocicletas, cuatriciclo, un autobomba y el apoyo de las divisiones Canes y Caballer\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Remarcaron que mantendr\u00e1n la vigilancia y prevenci\u00f3n en el resto de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El accionar responde a lineamientos del Ministerio de Seguridad, con la Subsecretar\u00eda de Seguridad y la Jefatura de Polic\u00eda a cargo del comisario general Alberto Arnaldo Molina y el comisario general, Jorge Andr\u00e9s Cristaldo, respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, durante todo el fin de semana habr\u00e1 un despliegue especial de polic\u00edas en trabajos de prevenci\u00f3n, teniendo en cuenta el amplio desplazamiento de personas en las \u00e1reas comerciales, en d\u00edas previos a las fiestas de fin de a\u00f1o, para que la poblaci\u00f3n pueda realizar sus compras con anticipaci\u00f3n y tranquilidad principalmente en la peatonal Jun\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las tiendas esperan que se vuelque un n\u00famero importante de personas para que realicen sus compras de Navidad y A\u00f1o Nuevo con tiempo en la jornada de ma\u00f1ana, en la que seguramente habr\u00e1 mucha gente recorriendo distintos puntos comerciales de la ciudad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Actividades del fin de semana<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Como cada fin de semana, la Municipalidad ofrece distintas alternativas para el p\u00fablico en general, visitantes y vecinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante este &#8220;finde&#8221;, de hoy al domingo, se llevar\u00e1n adelante m\u00faltiples actividades culturales y de entretenimiento en diversos puntos de la capital correntina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Feria de Artesanos estar\u00e1 hoy en la plaza Cabral, de 9 a 21; mientras que ma\u00f1ana y el domingo -en el mismo horario- se desarrollar\u00e1 en un nuevo espacio, ubicado sobre avenida costanera Juan Pablo II y Las Heras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ambos lugares, los feriantes ofrecer\u00e1n productos realizados en madera, hierro, adem\u00e1s de tejidos, entre otras manualidades, como as\u00ed tambi\u00e9n floricultura, dulces y platos regionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto que tambi\u00e9n para la jornada de hoy se realizar\u00e1 la entrega de premios &#8220;Maratones Barriales&#8221;, a las 10, en el Sal\u00f3n de Reuniones de la Secretar\u00eda de Turismo y Deportes (25 de Mayo 730).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De 16 a 18, en playa Arazaty se llevar\u00e1 a cabo la charla &#8220;Diversi\u00f3n Responsable&#8221; sobre educaci\u00f3n sexual integral, alimentaci\u00f3n sana y consumo responsable, adem\u00e1s se realizar\u00e1n juegos y funcionar\u00e1 una Estaci\u00f3n Saludable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, de 17 a 20, en el Dispositivo Territorial Comunitario (DTC) del barrio Independencia (Calle 658 al 2100), se har\u00e1 el cierre del a\u00f1o del programa &#8220;La comunidad comparte&#8221;, con los equipos que trabajan con los vecinos. Est\u00e1n previstas demostraciones de los trabajos realizados en el dispositivo, al igual que la actuaci\u00f3n de una murga y una banda de cumbia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, a las 19, se realizar\u00e1 el cierre de a\u00f1o en las escalinatas de la Legislatura provincial, a las 19 en Salta 545. Habr\u00e1 participaci\u00f3n municipal a trav\u00e9s del patio gastron\u00f3mico y expo de emprendedores que se sumar\u00e1n a la presentaci\u00f3n de elencos estables del Senado y artistas invitados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco de la conmemoraci\u00f3n del 2\u00ba aniversario de la declaraci\u00f3n del Chamam\u00e9 como Patrimonio Inmaterial Cultural de la Humanidad, se inaugurar\u00e1, a las 19, la segunda etapa del Sendero de la Memoria en el Paseo de los Chamameceros (avenida Costanera General San Mart\u00edn y Tom\u00e1s Edison).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta ocasi\u00f3n actuar\u00e1n los conjuntos San Antonio, Ra\u00edz Chamamecera, Corrientes Norte Academias y bailarines invitados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, como cierre de fin de a\u00f1o de los cursos &#8220;Crear +&#8221; se realizar\u00e1 una muestra de trabajos, exposici\u00f3n de obras y m\u00fasica en vivo a las 20 en el Centro Cultural &#8220;El Nido 38-G&#8221; (La Rioja 455).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El amplio operativo contar\u00e1 con 130 efectivos policiales, acompa\u00f1ados de grupos especiales, m\u00f3viles, motocicletas y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=368"}],"version-history":[{"count":2,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/368\/revisions"}],"predecessor-version":[{"id":371,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/368\/revisions\/371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/369"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}