{"id":354,"date":"2022-11-29T13:25:56","date_gmt":"2022-11-29T13:25:56","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=354"},"modified":"2022-11-29T13:25:56","modified_gmt":"2022-11-29T13:25:56","slug":"esquina-habria-dos-hombres-masligados-al-crimen-de-joaquin-perez","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2022\/11\/29\/esquina-habria-dos-hombres-masligados-al-crimen-de-joaquin-perez\/","title":{"rendered":"ESQUINA: HABR\u00cdA DOS HOMBRES M\u00c1SLIGADOS AL CRIMEN DE JOAQU\u00cdN P\u00c9REZ"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El hallazgo de casi cuatro millones de pesos en la casa de la mujer imputada por el homicidio, m\u00e1s las c\u00e1maras de seguridad de la zona, son la clave de los investigadores. Buscan a dos hombres que huyeron en moto y posiblemente se llevaron el arma homicida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a que por el momento el arma homicida no aparece, todas las pruebas recogidas por el fiscal de Esquina Juan Domingo Ram\u00edrez apuntan a que &#8220;Yuca&#8221; Godoy, la novia de Joaqu\u00edn P\u00e9rez, lo habr\u00eda asesinado de un escopetazo en el rostro, mientras que su vecino y quien dio aviso a la Polic\u00eda fue imputado por encubrimiento. Ambos ahora est\u00e1n con prisi\u00f3n preventiva; pero no ser\u00edan los \u00fanicos responsables del hecho, ya que en las \u00faltimas horas surgieron nuevas pistas que se desprender\u00edan de videos de seguridad, por lo que la Justicia podr\u00eda pedir en cuesti\u00f3n de horas, nuevos allanamientos. El hallazgo de una suma cercana a los cuatro millones de pesos en la casa de la acusada es otro dato clave y que sorprendi\u00f3 hasta a los propios sabuesos de la causa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Evel\u00edn &#8220;Yuca&#8221; Godoy, de 29 a\u00f1os, era pareja de la v\u00edctima y fue detenida la misma noche en la que atacaron a balazos a Joaqu\u00edn P\u00e9rez de 22 a\u00f1os. La joven, quien ya tendr\u00eda adem\u00e1s otra causa penal abierta, seg\u00fan indicaron algunas fuentes consultadas, intent\u00f3 desentenderse de la agresi\u00f3n, pero todas las pruebas la incriminar\u00edan. Al parecer hubo una fuerte discusi\u00f3n entre ella y P\u00e9rez la noche del 21 de noviembre, de la cual Esp\u00edndola, un vecino cuya casa da justo al pasillo donde se precipitaron los hechos, hab\u00eda prefiri\u00f3 ocult\u00e1rselo a la Polic\u00eda. Podr\u00eda haber sido incluso \u00e9l quien llam\u00f3 al 101 para reportar la presencia de una persona herida. Una fuente indic\u00f3 ayer a este medio que durante uno de los allanamientos a la casa de Godoy, la Polic\u00eda se encontr\u00f3 con una sorpresa imprevista. Sobre una mesa hallaron casi cuatro millones de pesos que podr\u00edan ser de alg\u00fan il\u00edcito, pero por no ser el objeto de investigaci\u00f3n, un juez orden\u00f3 liberarlo para que lo retire el abogado de la acusada, aunque el detalle no escapa a los investigadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan las c\u00e1maras de seguridad de un vecino, y de varios comercios de la zona, del lugar del crimen salieron a alta velocidad otros dos sujetos a bordo de una motocicleta. Pruebas sobre las que trabaja la Polic\u00eda. Debido a que a\u00fan es el arma homicida la que no aparece luego de varios allanamientos, se sospecha que estos sujetos pudieron haberla llevado de la escena, para evitar relacionarlos. Mientras tanto, polic\u00edas de Investigaciones de la Unidad Regional II de Goya est\u00e1n llevando a cabo los peritajes en los cinco tel\u00e9fonos celulares incautados, para tratar de identificar a los otros sospechosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos Imputados<br>El fiscal subrogante Juan Domingo Ram\u00edrez hall\u00f3 a Godoy responsable del &#8220;homicidio calificado, agravado por el v\u00ednculo&#8221; de Joaqu\u00edn P\u00e9rez y pidi\u00f3 prisi\u00f3n preventiva para ella. En tanto a D. Esp\u00edndola de 41 a\u00f1os, se lo acus\u00f3 de encubrimiento agravado y pidi\u00f3 igual coerci\u00f3n, aunque la diferencia est\u00e1 que la mujer continuar\u00e1 detenida hasta que se lleve a cabo el juicio, mientras que el hombre s\u00f3lo estar\u00e1 un mes detenido y podr\u00e1 llegar en libertad a las jornadas de debate. El jueves pasado, el juez de garant\u00edas de Esquina escuch\u00f3 los argumentos dados por el fiscal Ram\u00edrez en la audiencia de formulaci\u00f3n de cargos, haciendo lugar a los pedidos del Ministerio P\u00fablico ordenando la prisi\u00f3n preventiva para ambos detenidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Hay m\u00e1s responsables&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Mientras tanto, Jos\u00e9 Luis P\u00e9rez, padre de Joaqu\u00edn, habl\u00f3 con \u00e9poca y sostuvo que &#8220;voy a seguir pidiendo que detengan a todos los que est\u00e1n relacionados al crimen de mi hijo. \u00c9l vio algo que no le gust\u00f3 y puso en riesgo a terceros, por eso lo asesinaron. Intent\u00f3 protegerse del disparo, pero sus asesinos se aseguraron de no fallar. Ac\u00e1 hay m\u00e1s gente involucrada. Gracias a que un vecino accedi\u00f3 a ceder las im\u00e1genes de video de su c\u00e1mara de seguridad, se puede ver a dos personas retirarse del lugar en una moto tras el hecho y hay otros videos que la Polic\u00eda est\u00e1 investigando. Esto no puede quedar impune. Nosotros como familia vamos a seguir exigiendo justicia para Joaqu\u00edn&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan relat\u00f3 Jos\u00e9 Luis, ayer volvieron a Esquina especialistas de la Polic\u00eda que ya se pusieron a trabajar con el peritaje de los videos. &#8220;Yo s\u00f3lo espero que la fiscal\u00eda avance m\u00e1s r\u00e1pido, porque esta gente se les va a escapar si no los atrapan. Conf\u00edo en que est\u00e1n llevando adelante la investigaci\u00f3n, pero s\u00e9 que hay m\u00e1s responsables y los queremos a todos presos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con respecto a su relaci\u00f3n con la expareja de su hijo, Jos\u00e9 Luis confirm\u00f3 que no ten\u00eda ning\u00fan trato. &#8220;Ella no ven\u00eda a mi casa, ni yo iba a la casa de ella. S\u00f3lo se que mi hijo ven\u00eda muy de vez en cuando desde que estaba con esa chica. Esa noche se fue bien de casa, ni siquiera hab\u00eda tomado, como para que digan que \u00e9l ten\u00eda ese problema. Esa chica andaba en algo ilegal y mi hijo probablemente intent\u00f3 que saliera y eso le cost\u00f3 la vida&#8221;, sostuvo el padre de Joaqu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los hechos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El crimen del joven ocurri\u00f3 la noche del 21 de noviembre cerca de las 22:30, seg\u00fan indicaron fuentes oficiales. Joaqu\u00edn hab\u00eda estado una hora antes en la casa de su hermana y de all\u00ed se retir\u00f3 diciendo que ir\u00eda a la casa de &#8220;Yuca&#8221; (Godoy). El ataque se habr\u00eda producido justo en el ingreso a la zona del pasillo ubicado por calle Mancini al 1500.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando la Polic\u00eda lleg\u00f3 al lugar, tras un llamado an\u00f3nimo, se encontraron con Joaqu\u00edn P\u00e9rez de 22 a\u00f1os herido de un escopetazo en el rostro. Todav\u00eda con signos vitales. Lo trasladaron hacia la capital correntina, donde a las pocas horas de ingresar le diagnosticaron muerte cerebral. Su fallecimiento se oficializ\u00f3 al d\u00eda siguiente, el 23 de noviembre cerca del mediod\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un par de horas despu\u00e9s del hallazgo, el fiscal orden\u00f3 la detenci\u00f3n del vecino que report\u00f3 el hecho y luego se detuvo a la novia, en cuya vivienda se realizaron allanamientos para dar con el arma homicida, que hasta el momento los investigadores no logran encontrar. La comisar\u00eda Primera por razones de jurisdicci\u00f3n llev\u00f3 adelante las actuaciones sumariales de rigor. Los detenidos est\u00e1n alojados en la comisar\u00eda de la Mujer y el Menor y en la comisar\u00eda Primera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hallazgo de casi cuatro millones de pesos en la casa de la mujer imputada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=354"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/354\/revisions"}],"predecessor-version":[{"id":356,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/354\/revisions\/356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/355"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}