{"id":255,"date":"2022-10-14T14:19:21","date_gmt":"2022-10-14T14:19:21","guid":{"rendered":"http:\/\/visioncorrientes.com\/?p=255"},"modified":"2022-10-24T22:29:16","modified_gmt":"2022-10-24T22:29:16","slug":"un-ex-intendente-de-chaco-fue-encontrado-sin-vida-en-su-domicilio","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2022\/10\/14\/un-ex-intendente-de-chaco-fue-encontrado-sin-vida-en-su-domicilio\/","title":{"rendered":"UN EX INTENDENTE DE CHACO FUE ENCONTRADO SIN VIDA EN SU DOMICILIO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Juli\u00e1n Benito Flores, hermano del ex funcionario, fue qui\u00e9n se dirigi\u00f3 a la casa y se encontr\u00f3 con la terrible escena.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"525\" src=\"http:\/\/visioncorrientes.com\/wp-content\/uploads\/2022\/10\/981318.png_nota.jpg\" alt=\"\" class=\"wp-image-256\" srcset=\"https:\/\/visioncorrientes.com\/wp-content\/uploads\/2022\/10\/981318.png_nota.jpg 700w, https:\/\/visioncorrientes.com\/wp-content\/uploads\/2022\/10\/981318.png_nota-300x225.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Esta ma\u00f1ana el ex intendente de la localidad de Puerto Vilelas, Ariel Flores fue encontrado sin vida en su domicilio por su hermano, Juli\u00e1n Benito Flores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El descubrimiento se origin\u00f3 en principio por la llamada de una oyente del programa radial, la mujer le expres\u00f3 para ver si pod\u00edan ubicar a una persona. &#8220;Ariel Flores, \u00e9l es de Vilelas me parece&#8221;, dijo la oyente a lo que el periodista respondi\u00f3: &#8220;S\u00ed, Arielito&#8221;, haciendo referencia al ex jefe comunal de la localidad de Puerto Vilelas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esa manera, la se\u00f1ora explic\u00f3 la situaci\u00f3n que estaba ocurriendo. &#8220;S\u00ed, vive ac\u00e1 cerquita, dej\u00f3 su perro en la casa desde antes de la tormenta y no hay nadie. Tiene las rejas muy cerradita y no se puede darle de comer, igual con los vecinos tratamos pero ah\u00ed est\u00e1 el perro solo&#8221;, se\u00f1al\u00f3 la oyente y a\u00f1adi\u00f3: &#8220;Donde nosotros estamos es en Villa San Mart\u00edn por la Sargento Cabral&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el llamado, se comunicaron con Juli\u00e1n Benito Flores (hermano de Ariel) y posteriormente se dirigi\u00f3 hasta la casa con un cerrajero. All\u00ed, Juli\u00e1n se encontr\u00f3 con la terrible noticia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, Diario Chaco&nbsp; se comunic\u00f3 con el jefe de prensa de la Polic\u00eda del Chaco, Alejandro Dom\u00ednguez, quien inform\u00f3 que hasta el momento no se sabe el motivo del deceso del ex intendente de Puerto Vilelas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juli\u00e1n Benito Flores, hermano del ex funcionario, fue qui\u00e9n se dirigi\u00f3 a la casa y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4,2,3,1],"tags":[],"class_list":["post-255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","category-internacionales","category-locales","category-nacionales","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=255"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/255\/revisions"}],"predecessor-version":[{"id":257,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/255\/revisions\/257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/256"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}