{"id":197,"date":"2022-09-22T16:36:38","date_gmt":"2022-09-22T16:36:38","guid":{"rendered":"http:\/\/visioncorrientes.com\/?p=197"},"modified":"2022-10-24T22:29:16","modified_gmt":"2022-10-24T22:29:16","slug":"rescataron-al-yacare-que-estaba-en-la-playa-era-acechado-por-malloneros-y-banistas","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2022\/09\/22\/rescataron-al-yacare-que-estaba-en-la-playa-era-acechado-por-malloneros-y-banistas\/","title":{"rendered":"RESCATARON AL YACAR\u00c9 QUE ESTABA EN LA PLAYA: ERA ACECHADO POR MALLONEROS Y BA\u00d1ISTAS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El traslado del animal estuvo a cargo del Centro de Conservaci\u00f3n Aguar\u00e1.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"440\" src=\"http:\/\/visioncorrientes.com\/wp-content\/uploads\/2022\/09\/1663849791300.webp\" alt=\"\" class=\"wp-image-198\" srcset=\"https:\/\/visioncorrientes.com\/wp-content\/uploads\/2022\/09\/1663849791300.webp 770w, https:\/\/visioncorrientes.com\/wp-content\/uploads\/2022\/09\/1663849791300-300x171.webp 300w, https:\/\/visioncorrientes.com\/wp-content\/uploads\/2022\/09\/1663849791300-768x439.webp 768w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Centro de Conservaci\u00f3n Aguar\u00e1 rescat\u00f3 al yacar\u00e9 que en los \u00faltimos d\u00edas hab\u00eda aparecido en la playa Arazaty de la ciudad de Corrientes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Catalina Mancedo, integrante de dicho centro, confirm\u00f3 a ellitoral.com.ar que el animal fue trasladado debido a que era acechado por los malloneros y los ba\u00f1istas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Esto no fue un logro, perdimos la batalla,\u00a0\u00a0<strong>la gente no entiende que debe mantener\u00a0distancia y respetar a la fauna silvestre<\/strong>&#8220;,\u00a0 afirm\u00f3.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, Mancedo se\u00f1al\u00f3 que es necesario que &#8220;toda la sociedad tiene que aprender a&nbsp;&nbsp;<strong>convivir con&nbsp;la presencia de los yacar\u00e9, monos caray\u00e1, lagartos overos<\/strong>,&nbsp; porque se viene un verano dif\u00edcil y estamos pasando por una sequ\u00eda&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>VER M\u00c1S:&nbsp;<a href=\"https:\/\/www.ellitoral.com.ar\/corrientes\/2022-9-19-1-0-0-preparan-un-protocolo-para-la-temporada-de-verano-ante-la-aparicion-de-un-yacare\">Preparan un protocolo para la temporada de verano ante la aparici\u00f3n de un yacar\u00e9<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, sostuvo que por las noches, cuando el animal no ten\u00eda custodia,&nbsp;&nbsp;<strong>&#8220;estaba siendo acechado por los malloneros y adem\u00e1s, la gente no manten\u00eda el distanciamiento, no manten\u00eda a sus perros con correa&#8221;.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Todav\u00eda nos queda mucho por trabajar, educar y tener empat\u00eda y de poder disfrutar de nuestra fauna silvestre sin tener que invadir o lastimar&#8221;, precis\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre tanto, remarc\u00f3: &#8220;Vamos a seguir apostando a&nbsp;&nbsp;<strong>la educaci\u00f3n ambiental<\/strong>&nbsp; desde el Centro Aguar\u00e1, esa es nuestra mejor herramienta para la conservaci\u00f3n de nuestra fauna silvestre&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por cuestiones de seguridad, no se revel\u00f3 el lugar al que fue llevado el yacar\u00e9.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El traslado del animal estuvo a cargo del Centro de Conservaci\u00f3n Aguar\u00e1.\u00a0 El Centro de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":198,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4,2,3,1],"tags":[],"class_list":["post-197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","category-internacionales","category-locales","category-nacionales","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=197"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/197\/revisions"}],"predecessor-version":[{"id":199,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/197\/revisions\/199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/198"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}