{"id":1303,"date":"2026-06-28T18:35:47","date_gmt":"2026-06-28T21:35:47","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=1303"},"modified":"2026-06-28T18:35:47","modified_gmt":"2026-06-28T21:35:47","slug":"a-la-espera-de-las-declaraciones-que-revelen-que-paso-con-loan","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2026\/06\/28\/a-la-espera-de-las-declaraciones-que-revelen-que-paso-con-loan\/","title":{"rendered":"A LA ESPERA DE LAS DECLARACIONES QUE REVELEN QU\u00c9 PAS\u00d3 CON LOAN"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Concluy\u00f3 la segunda semana en el primer juicio por la desaparici\u00f3n de Loan Pe\u00f1a, el ni\u00f1o de 9 de Julio del que nada se sabe desde ese almuerzo en la casa de su abuela en el paraje rural El Algarrobal el 13 de junio de 2024. Transcurrieron las cuatro primeras jornadas del debate en que solo dos de los 17 imputados dieron alg\u00fan tipo de explicaci\u00f3n ante los jueces. Pasaron las primeras oportunidades para que ese insano pero, hasta ahora, inexpugnable pacto de silencio se quiebre y se sepa qu\u00e9 pas\u00f3 con el peque\u00f1o. Mientras, se espera que los padres del chico, Jos\u00e9 y Mar\u00eda, y los cinco hermanos (todos los mayores de edad) presten declaraci\u00f3n en la continuaci\u00f3n del juicio el pr\u00f3ximo martes 30 de junio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El juicio tiene sentados en el banquillo de los acusados a 17 imputados, pero en dos causas diferentes. El primer grupo est\u00e1 integrado por aquellos que participaron del almuerzo. Se los juzga bajo los cargos de sustracci\u00f3n de un menor, ocultamiento y encubrimiento. Son siete: Laudelina Pe\u00f1a, t\u00eda del ni\u00f1o; Bernardino Antonio Ben\u00edtez, t\u00edo pol\u00edtico de Loan; Carlos Guido P\u00e9rez, capit\u00e1n de nav\u00edo retirado; Mar\u00eda Victoria Caillava, exfuncionaria municipal y esposa de Carlos P\u00e9rez; Daniel \u201cFierrito\u201d Ram\u00edrez, amigo de la familia; M\u00f3nica del Carmen Millapi, esposa de Ram\u00edrez; y Walter Adri\u00e1n Maciel, excomisario del pueblo de 9 de Julio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A los otros imputados se los conoce como \u201cLa banda del hotel\u201d o por su pertenencia o relaci\u00f3n con la Fundaci\u00f3n Dupuy. Llegaron a juicio unificado bajo los cargos de entorpecimiento de la investigaci\u00f3n, privaci\u00f3n ileg\u00edtima de la libertad y defraudaci\u00f3n a la administraci\u00f3n p\u00fablica. Son diez: Gabriel Soria (\u201cEl Americano\u201d), Alan Ca\u00f1ete, Elizabeth Noem\u00ed Cutaia, Federico Rossi Colombo, Valeria Liliana L\u00f3pez, Ver\u00f3nica Paola Machuca Yunis, Pablo Gabriel N\u00fa\u00f1ez, Pablo Javier Noguera, Leonardo Daniel Rubio y Delfina Taborda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada uno de ellos tuvo la oportunidad de dar su primera versi\u00f3n ante el Tribunal que los juzga. Ninguno de los siete imputados con la car\u00e1tula m\u00e1s dura \u0097la de sustracci\u00f3n del ni\u00f1o\u0097 declar\u00f3. Todos hicieron uso de su derecho de no hablar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El que s\u00ed se dirigi\u00f3 a los jueces fue Alan Ca\u00f1ete, uno de la decena de imputados por el entorpecimiento de la investigaci\u00f3n. Habl\u00f3 durante dos horas. Lo primero que hizo fue rechazar la imputaci\u00f3n de privaci\u00f3n ileg\u00edtima de la libertad. \u201cLlegamos a Corrientes para buscar a Loan con el estudio de la doctora Cutaia. No vine a entorpecer. Pusieron eso, pero no mis especialidades ni antecedentes de trabajo\u201d, destac\u00f3 Ca\u00f1ete, quien coment\u00f3 que es criminalista, periodista y sus especialidades hacen referencia al trabajo por y para defender los derechos de los ni\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insisti\u00f3 en que llegaron en nombre de Ram\u00f3n Dupuy, quien en las primeras semanas sali\u00f3 ante los medios de comunicaci\u00f3n contando del apoyo al grupo de personas que viaj\u00f3 hasta 9 de Julio para colaborar en lo que sea necesario para la b\u00fasqueda de Loan y brindar resguardo y protecci\u00f3n a los dem\u00e1s ni\u00f1os que estuvieron ese 13 de junio de 2024 con el peque\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un disparate judicial lo que hizo el Ministerio Publico Fiscal. Ellos desv\u00edan la investigaci\u00f3n. No vinimos con dolo y no conozco a las personas a quienes se les imputa el delito de sustracci\u00f3n. Los ni\u00f1os no estaban privados de su libertad, no estaban con candados en sus habitaciones. Se les brind\u00f3 comida, abrigo, hasta zapatillas, tanto a los chicos como a Macarena y Camila\u201d, indic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras su declaraci\u00f3n, tanto su defensa como por parte del Ministerio Publico Fiscal realizaron un interrogatorio. Fue un ida y vuelta de acusaciones y respuestas que en algunas oportunidades no dejaban en claro su rol dentro del grupo de profesionales que llegaron desde Buenos Aires con el prop\u00f3sito de localizar al menor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su declaraci\u00f3n se sumaron pruebas, una de ellas una fotograf\u00eda de una lapicera que Cristina Pozzer Penzo, jueza de Goya, le regal\u00f3 por estar \u201corgullosa de su trabajo con los ni\u00f1os\u201d, dijo su abogado, quien intent\u00f3 continuar con la presentaci\u00f3n de m\u00e1s fotograf\u00eda, pero su pretensi\u00f3n fue rechazada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La \u00faltima de los 17 acusados que se sent\u00f3 frente a los jueces fue Valeria L\u00f3pez. Y declar\u00f3. Pero a medias. \u201cEl d\u00eda 4 (de julio de 2024) viaj\u00e9 a Corrientes para contenci\u00f3n. Pagu\u00e9 los costos del viaje de mi bolsillo. Llegu\u00e9 al hotel El Despertar y qued\u00e9 hasta el 9. Mi tarea fue la de contenci\u00f3n. Estuve cinco d\u00edas, siempre mi labor fue social. A veces cocinaba o limpiaba, colaboraba porque en el hotel hab\u00eda ese servicio. Yo era el sost\u00e9n en lo que faltaba. Estuve esos d\u00edas y otra cosa no hice\u201d, coment\u00f3 de manera escueta. Cuando se le pregunt\u00f3 si iba a responder preguntas a las partes, se neg\u00f3, concluy\u00f3 su declaraci\u00f3n y tom\u00f3 nuevamente su lugar entre los acusados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concluy\u00f3 la segunda semana en el primer juicio por la desaparici\u00f3n de Loan Pe\u00f1a, el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-1303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=1303"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1303\/revisions"}],"predecessor-version":[{"id":1305,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1303\/revisions\/1305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/1304"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=1303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=1303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=1303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}