{"id":1288,"date":"2026-06-19T22:50:08","date_gmt":"2026-06-20T01:50:08","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=1288"},"modified":"2026-06-24T22:53:28","modified_gmt":"2026-06-25T01:53:28","slug":"con-apoyo-del-gobierno-provincial-corrientes-recibira-el-raid-nautico-de-las-americas","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2026\/06\/19\/con-apoyo-del-gobierno-provincial-corrientes-recibira-el-raid-nautico-de-las-americas\/","title":{"rendered":"CON APOYO DEL GOBIERNO PROVINCIAL, CORRIENTES RECIBIR\u00c1 EL RAID N\u00c1UTICO DE LAS AM\u00c9RICAS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La competencia de lanchas de velocidad sobre el r\u00edo Paran\u00e1 fue presentada en Corrientes Capital. El evento busca consolidarse como uno de los encuentros n\u00e1uticos m\u00e1s importantes de la regi\u00f3n, combinando deporte, turismo y aventura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno de Corrientes, a trav\u00e9s del Ministerio de Turismo, y la Secretar\u00eda de Deportes, junto a la Municipalidad de la ciudad de Corrientes presentaron el Raid N\u00e1utico de las Am\u00e9ricas, un evento que apuesta al desarrollo tur\u00edstico y deportivo en Corrientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presentaci\u00f3n tuvo lugar en el Hotel Marriott donde se brindaron detalles sobre las jornadas de carreras de lanchas de velocidad que se desarrollar\u00e1n sobre el r\u00edo Paran\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propuesta reuni\u00f3 a organizadores y referentes del sector tur\u00edstico y deportivo en torno a una iniciativa que busca potenciar el atractivo de los paisajes correntinos y fortalecer la actividad n\u00e1utica en la regi\u00f3n. El Raid N\u00e1utico de las Am\u00e9ricas combinar\u00e1 velocidad, deporte y aventura, con un recorrido que pondr\u00e1 en valor uno de los principales recursos naturales de la provincia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posicionar a Corrientes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, el secretario de Gesti\u00f3n y Planificaci\u00f3n del Ministerio de Turismo, H\u00e9ctor D\u00e1vila explic\u00f3 que \u201cdentro de los ejes de gesti\u00f3n que nos puso el Gobernador es posicionar a la provincia en eventos que puedan traer turistas y claramente este es uno de ellos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ser consultado sobre este evento deportivo, el secretario de Deportes, Jorge Terrile expres\u00f3 que &#8220;nosotros tenemos un escenario natural que es extraordinario como el r\u00edo Paran\u00e1, que nos permite realizar esta puesta en acci\u00f3n de lo que es este raid n\u00e1utico\u201d y en ese sentido, destac\u00f3 el respaldo por parte del Gobierno provincial a la disciplina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el intendente de la ciudad de Corrientes, Claudio Polich manifest\u00f3 que \u201ces importante poner a Corrientes dentro de un calendario de competencia internacional de moton\u00e1utica\u201d y agreg\u00f3 que \u201cqueremos realzar todo lo que es Corrientes y su visi\u00f3n hacia el r\u00edo&#8221; por eso &#8220;esta competencia es una de las formas de poner en valor a la ciudad&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, Joaqu\u00edn Chama, en representaci\u00f3n del sector privado remarc\u00f3 la importancia de continuar trabajando de manera coordinada entre el p\u00fablico y privado para potenciar a Corrientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Sebasti\u00e1n Alba, uno de los organizadores coment\u00f3 que llevan adelante m\u00e1s de 40 competencias de este tipo y apuestan a qu\u00e9 &#8220;Corrientes sea una sede con fecha fija&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la oportunidad, participaron de la presentaci\u00f3n el presidente de la C\u00e1mara de Diputados de la Provincia de Corrientes, Eduardo Tassano, y el secretario de Turismo y Deportes de la Municipalidad de la Ciudad de Corrientes, Jos\u00e9 Sand.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detalles de la competencia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las actividades se desarrollar\u00e1n frente a la Playa Arazaty, entre las 13 y 14 horas. El s\u00e1bado 27 tendr\u00e1 lugar la tradicional carrera de los 100 km, una prueba de larga duraci\u00f3n en la que los participantes deber\u00e1n completar un recorrido marcado por distintos puntos de control en el menor tiempo posible. En tanto, el domingo 28 se disputar\u00e1 una competencia en circuito boyado, con tres mangas por categor\u00eda y una duraci\u00f3n total de tres horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la oportunidad, participar\u00e1n embarcaciones de las categor\u00edas Libre, Intermedia, hasta 2100 cc V4, hasta 1600 cc y hasta 1100 cc, en un encuentro que combina deporte, recreaci\u00f3n y turismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante ambas jornadas se contar\u00e1 con el acompa\u00f1amiento de Prefectura Naval Argentina, que garantizar\u00e1 la seguridad de la competencia mediante la suspensi\u00f3n temporal del tr\u00e1nsito de embarcaciones en la zona de carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera, se invita a toda la ciudadan\u00eda a presenciar el espect\u00e1culo desde cualquier punto de la costanera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La competencia de lanchas de velocidad sobre el r\u00edo Paran\u00e1 fue presentada en Corrientes Capital. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,21],"tags":[],"class_list":["post-1288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","category-sociedad"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=1288"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1288\/revisions"}],"predecessor-version":[{"id":1290,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1288\/revisions\/1290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/1289"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=1288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=1288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=1288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}