{"id":1230,"date":"2026-05-21T21:55:49","date_gmt":"2026-05-21T21:55:49","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=1230"},"modified":"2026-06-05T21:56:13","modified_gmt":"2026-06-05T21:56:13","slug":"paso-de-la-patria-vivio-una-exitosa-jornada-de-pesca-adaptada","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2026\/05\/21\/paso-de-la-patria-vivio-una-exitosa-jornada-de-pesca-adaptada\/","title":{"rendered":"PASO DE LA PATRIA VIVI\u00d3 UNA EXITOSA JORNADA DE PESCA ADAPTADA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este mi\u00e9rcoles 21 de mayo, la localidad de Paso de la Patria tuvo una emotiva jornada en el marco del Primer Encuentro de Pesca Adaptada, realizado en el parador La Costa, a orillas del r\u00edo Paran\u00e1. El evento de gran trascendencia sent\u00f3 un precedente al convertirse en el primero de futuras propuestas de este tipo en la provincia de Corrientes y en la regi\u00f3n.<br>La actividad reuni\u00f3 a 137 personas inscriptas, quienes disfrutaron de una jornada inclusiva y recreativa pensada para compartir una experiencia \u00fanica en contacto con la naturaleza. Adem\u00e1s, se ofrecieron paseos en lancha gratuitos, actividades de pesca, m\u00fasica en vivo y desayuno para todos los participantes, generando un ambiente de alegr\u00eda, integraci\u00f3n y emoci\u00f3n.<br>Familias enteras pudieron disfrutar de un d\u00eda inolvidable frente al r\u00edo, destac\u00e1ndose la importancia de seguir promoviendo espacios accesibles e inclusivos para toda la comunidad.<br>En representaci\u00f3n del Gobierno provincial asistieron el ministro de Desarrollo Social Jos\u00e9 Irigoyen y el secretario de Coordinaci\u00f3n del Ministerio de Turismo H\u00e9ctor D\u00e1vila quienes fueron recibidos por el intendente de Paso de la Patria Oscar Armando Garc\u00eda, la viceintendente local Estela Vill\u00e1n y el presidente del Instituto de Cultura y Turismo Alfredo Blanco. En tanto que tambi\u00e9n acompa\u00f1aron la directora de Turismo Ayel\u00e9n Zalazar y el director de Cultura Maximiliano Canteros, y miembros del equipo t\u00e9cnico de dicho organismo municipal.<br>Desde la organizaci\u00f3n destacaron que Paso de la Patria trabaja arduamente para consolidarse como un destino tur\u00edstico inclusivo y accesible para todos, promoviendo actividades que permitan la integraci\u00f3n y participaci\u00f3n de cada persona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles 21 de mayo, la localidad de Paso de la Patria tuvo una emotiva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=1230"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1230\/revisions"}],"predecessor-version":[{"id":1232,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1230\/revisions\/1232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/1231"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=1230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=1230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=1230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}