{"id":1151,"date":"2026-02-17T12:27:14","date_gmt":"2026-02-17T12:27:14","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=1151"},"modified":"2026-02-17T12:27:14","modified_gmt":"2026-02-17T12:27:14","slug":"la-china-suarez-hablo-de-la-polemica-con-wanda-nara-por-la-malla-de-su-hija","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2026\/02\/17\/la-china-suarez-hablo-de-la-polemica-con-wanda-nara-por-la-malla-de-su-hija\/","title":{"rendered":"LA CHINA SU\u00c1REZ HABL\u00d3 DE LA POL\u00c9MICA CON WANDA NARA POR LA MALLA DE SU HIJA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La actriz, en di\u00e1logo con Gustavo M\u00e9ndez para La ma\u00f1ana con Moria, se refiri\u00f3 al esc\u00e1ndalo por la prenda en medio del esc\u00e1ndalo judicial<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las versiones cruzadas sobre la relaci\u00f3n entre los hijos de&nbsp;<strong>Wanda Nara&nbsp;y&nbsp;Mauro Icardi&nbsp;con la familia de&nbsp;la China Su\u00e1rez&nbsp;<\/strong>volvieron a ocupar el centro del debate medi\u00e1tico, luego de que la conductora de&nbsp;MasterChef Celebrity&nbsp;lanzara una acusaci\u00f3n directa:&nbsp;<strong>\u201cQue ella se deje de usar mi ropa y la de mis hijas. Y que devuelva mi mudanza\u201d<\/strong>,&nbsp;exigi\u00f3 la conductora, en referencia a pertenencias que, seg\u00fan ella, no regresaron de Turqu\u00eda. La disputa se da en medio de las tensiones judiciales que ambas familias atraviesan tras su separaci\u00f3n.<br><br>La controversia surgi\u00f3 tras el cumplea\u00f1os de la hija menor de la actriz, evento al que Icardi intent\u00f3 que asistieran sus hijas, seg\u00fan detall\u00f3 su abogada,&nbsp;Elba Marcovecchio. La letrada hab\u00eda recalcado en DDM (Am\u00e9rica TV) la importancia de los adultos en las familias ensambladas:<strong>&nbsp;\u201cCuando uno habla del ensamble de familias, es muy importante el rol que toman los adultos\u201d<\/strong>, aunque evit\u00f3 brindar detalles sobre la causa judicial \u201cpor la privacidad de las ni\u00f1as\u201d. Aclar\u00f3, sin embargo, que el pedido de concurrencia fue espont\u00e1neo de las menores hacia su padre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El trasfondo de la disputa revel\u00f3 el desaf\u00edo de establecer v\u00ednculos en familias ensambladas. Marcovecchio defendi\u00f3 la postura de Icardi y resalt\u00f3:&nbsp;<strong>\u201c\u00c9l sabe lo que es una familia ensamblada. \u00c9l vive una familia ensamblada\u201d.&nbsp;<\/strong>No obstante, el conflicto por la ropa y los objetos personales expuso la fragilidad de esos lazos y la desconfianza que persiste. Wanda Nara fue tajante respecto al v\u00ednculo de sus hijas con la China:&nbsp;\u201cMis hijas no la sienten ni tienen la obligaci\u00f3n de sentir familia a una mujer con tan pocos valores\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hab\u00eda sido la malla que us\u00f3 una de las hijas de la actriz la que motiv\u00f3 el enojo de la animadora&nbsp;<strong>al asegurar que esa es una de las prendas de una de sus hijas que qued\u00f3 en Turqu\u00eda.<\/strong>&nbsp;Fue en&nbsp;La ma\u00f1ana con Moria&nbsp;(El Trece) en el que el periodista&nbsp;Gustavo M\u00e9ndez&nbsp;transmiti\u00f3 su charla con la China sobre la pol\u00e9mica.&nbsp;\u201cHabl\u00e9 con ella y se re\u00eda. Otra mentira m\u00e1s. Cuando fueron a Miami y se comprometieron, volvieron y se encontraron en \u2018La casa de los sue\u00f1os\u2019. Ah\u00ed \u00e9l les llen\u00f3 el cuarto de regalos\u201d, record\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando fue la China le compr\u00f3 esa misma malla a su hija porque sab\u00eda que le gustaba. Esa malla es tres talles m\u00e1s grande para su hija, porque tambi\u00e9n le gustaba. Es de frutilitas\u201d. As\u00ed el panelista dio la versi\u00f3n de la protagonista de&nbsp;Hija del fuego&nbsp;y desminti\u00f3 que su hija us\u00f3 ropa ajena sin consentimiento.&nbsp;<strong>\u201cNo la us\u00f3, pero se instal\u00f3 desde el lado de Wanda Nara que le hab\u00edan sacado la malla\u201d<\/strong>, agreg\u00f3 M\u00e9ndez.<br>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No solo las pertenencias materiales generaron conflicto, sino tambi\u00e9n la din\u00e1mica en redes sociales.&nbsp;Moria Cas\u00e1n&nbsp;hizo hincapi\u00e9 en c\u00f3mo gestos m\u00ednimos del entorno, como los \u201clikes\u201d de&nbsp;Kenny Palacios&nbsp;\u2014persona de confianza de Wanda\u2014 a publicaciones de la China, se convierten en combustible para la pol\u00e9mica:&nbsp;<strong>\u201cKenny, astuto tambi\u00e9n, pone cosas como para que se hable de \u00e9l\u201d.<\/strong>&nbsp;Seg\u00fan los panelistas, estos movimientos, lejos de ser inocentes, amplifican el alcance de rumores y versiones infundadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras la controversia medi\u00e1tica se alimenta de acusaciones y desmentidas,&nbsp;Moria Cas\u00e1n&nbsp;fue muy dura sobre el verdadero eje del conflicto:<strong>&nbsp;\u201cSalvo en alg\u00fan que otro lado, los que menos piensan en los chicos son ellos\u201d<\/strong>. La frase apunt\u00f3 a la paradoja de un enfrentamiento que, aunque se justifica en nombre de los menores, termina desplazando sus necesidades frente a la exposici\u00f3n p\u00fablica y la batalla de relatos entre adultos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace una semana las declaraciones de&nbsp;<strong>la&nbsp;representante legal de&nbsp;Mauro Icardi&nbsp;sobre la din\u00e1mica familiar tras el cumplea\u00f1os de la hija menor de&nbsp;la China Su\u00e1rez<\/strong>, motivaron la reacci\u00f3n de&nbsp;Wanda Nara. Molesta, la animadora se comunic\u00f3 con el periodista&nbsp;Guido Z\u00e1ffora&nbsp;para lanzar nuevas acusaciones y cuestionamientos directos al entorno de su expareja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actriz, en di\u00e1logo con Gustavo M\u00e9ndez para La ma\u00f1ana con Moria, se refiri\u00f3 al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=1151"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1151\/revisions"}],"predecessor-version":[{"id":1153,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1151\/revisions\/1153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/1152"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=1151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=1151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=1151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}