{"id":1128,"date":"2026-01-22T12:53:00","date_gmt":"2026-01-22T12:53:00","guid":{"rendered":"https:\/\/visioncorrientes.com\/?p=1128"},"modified":"2026-01-22T12:53:01","modified_gmt":"2026-01-22T12:53:01","slug":"milei-el-capitalismo-de-libre-empresa-es-el-unico-sistema-justo","status":"publish","type":"post","link":"https:\/\/visioncorrientes.com\/index.php\/2026\/01\/22\/milei-el-capitalismo-de-libre-empresa-es-el-unico-sistema-justo\/","title":{"rendered":"MILEI: &#8220;EL CAPITALISMO DE LIBRE EMPRESA ES EL \u00daNICO SISTEMA JUSTO&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El mandatario participa de la cumbre econ\u00f3mica en Suiza con una agenda marcada por reuniones con l\u00edderes internacionales. Habl\u00f3 Donald Trump y se reaviv\u00f3 el debate geopol\u00edtico que atraviesa el encuentro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Javier Milei&nbsp;participa este mi\u00e9rcoles del Foro Econ\u00f3mico Mundial de Davos, donde expondr\u00e1 su mirada&nbsp;<strong>sobre el escenario internacional y ratificar\u00e1 el alineamiento de la Argentina con Estados Unidos.<\/strong>&nbsp;El presidente mantiene una agenda intensa que incluye reuniones con l\u00edderes pol\u00edticos y empresarios, en una edici\u00f3n marcada por la tensi\u00f3n entre Washington y Europa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Milei&nbsp;brinda un discurso ante el Foro Econ\u00f3mico de Davos, donde afirm\u00f3 que&nbsp;\u201cel capitalismo de libre comercio es el \u00fanico sistema justo&#8221;.&nbsp;<strong>\u201cEl socialismo suena lindo, pero termina mal\u201d<\/strong>, sostuvo el mandatario nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su discurso tiene lugar luego del de su par de Estados Unidos,&nbsp;Donald Trump,&nbsp;<strong>quien volvi\u00f3 a reavivar la pol\u00e9mica por Groenlandia<\/strong>&nbsp;y lanz\u00f3 advertencia a Europa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl capitalismo de libre empresa es el \u00fanico sistema justo. Se reconocen dos derechos fundamentales: la vida y la libertad.&nbsp;<strong>En paralelo tenemos derechos adquiridos ganados por merecimiento, el de la propiedad privada<\/strong>\u201d,&nbsp;indic\u00f3. A su entender, \u201cresulta inadmisible sacrificar a la justicia en el altar de la eficiencia\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;En 2024 afirm\u00e9 que Occidente estaba en peligro.&nbsp;<strong>El socialismo siempre termina mal. Las pol\u00edticas socialistas enga\u00f1an a personas nobles y bellas<\/strong>. Con el socialismo vemos lo aberrante que sucedi\u00f3 en Venezuela\u201d, resalt\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mandatario participa de la cumbre econ\u00f3mica en Suiza con una agenda marcada por reuniones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=1128"}],"version-history":[{"count":1,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1128\/revisions"}],"predecessor-version":[{"id":1130,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/posts\/1128\/revisions\/1130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media\/1129"}],"wp:attachment":[{"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=1128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=1128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioncorrientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=1128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}